{"id":56328,"date":"2025-02-20T08:04:29","date_gmt":"2025-02-20T08:04:29","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/"},"modified":"2025-10-07T10:50:47","modified_gmt":"2025-10-07T10:50:47","password":"","slug":"uprava-zamestnanca-v-registri-zamestnancov","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/","title":{"rendered":"\u00daprava zamestnanca v registri zamestnancov"},"content":{"rendered":"\n<p>Ak potrebujete aktualizova\u0165 inform\u00e1cie o existuj\u00facom zamestnancovi:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Prejdite do \u010dasti<strong> Zdroje<\/strong> a vyberte polo\u017eku <strong>Person\u00e1lny register<\/strong>.<\/li>\n\n\n\n<li>Potom na paneli person\u00e1lu kliknite na <strong>ikonu ceruzky<\/strong> vpravo od zamestnanca, ktor\u00e9ho chcete upravi\u0165.<\/li>\n\n\n\n<li>Na \u010fal\u0161om paneli nap\u00ed\u0161te nov\u00e9 inform\u00e1cie, ktor\u00e9 chcete aktualizova\u0165.<\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"447\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126-1024x447.png\" alt=\"\" class=\"wp-image-52639\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126-1024x447.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126-300x131.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126-768x335.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126-360x157.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126.png 1167w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Nakoniec kliknite na tla\u010didlo <strong>Ulo\u017ei\u0165<\/strong>.<\/li>\n<\/ul>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ak potrebujete aktualizova\u0165 inform\u00e1cie o existuj\u00facom zamestnancovi:<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[2127],"doc_tag":[],"class_list":["post-56328","docs","type-docs","status-publish","hentry","doc_category-personalny-register"],"acf":[],"year_month":"2026-07","word_count":55,"total_views":"157","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/sk\/author\/bettina\/"},"doc_category_info":[{"term_name":"Person\u00e1lny register","term_url":"https:\/\/skyplanner.ai\/sk\/docs-category\/personalny-register\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00daprava zamestnanca v registri zamestnancov &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00daprava zamestnanca v registri zamestnancov\" \/>\n<meta property=\"og:description\" content=\"Ak potrebujete aktualizova\u0165 inform\u00e1cie o existuj\u00facom zamestnancovi:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T10:50:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1167\" \/>\n\t<meta property=\"og:image:height\" content=\"509\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/\",\"url\":\"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/\",\"name\":\"\u00daprava zamestnanca v registri zamestnancov &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/sk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126-1024x447.png\",\"datePublished\":\"2025-02-20T08:04:29+00:00\",\"dateModified\":\"2025-10-07T10:50:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/#breadcrumb\"},\"inLanguage\":\"sk-SK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/#primaryimage\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126-1024x447.png\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126-1024x447.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/sk\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/sk\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00daprava zamestnanca v registri zamestnancov\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/sk\/#website\",\"url\":\"https:\/\/skyplanner.ai\/sk\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/sk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/sk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sk-SK\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/sk\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/sk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\/\/skyplanner.ai\/sk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/sk\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00daprava zamestnanca v registri zamestnancov &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/","og_locale":"sk_SK","og_type":"article","og_title":"\u00daprava zamestnanca v registri zamestnancov","og_description":"Ak potrebujete aktualizova\u0165 inform\u00e1cie o existuj\u00facom zamestnancovi:","og_url":"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T10:50:47+00:00","og_image":[{"width":1167,"height":509,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/","url":"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/","name":"\u00daprava zamestnanca v registri zamestnancov &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/sk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126-1024x447.png","datePublished":"2025-02-20T08:04:29+00:00","dateModified":"2025-10-07T10:50:47+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/#breadcrumb"},"inLanguage":"sk-SK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/"]}]},{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126-1024x447.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-126-1024x447.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/sk\/docs\/uprava-zamestnanca-v-registri-zamestnancov\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/sk\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/sk\/docs\/"},{"@type":"ListItem","position":3,"name":"\u00daprava zamestnanca v registri zamestnancov"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/sk\/#website","url":"https:\/\/skyplanner.ai\/sk\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/sk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/sk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sk-SK"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/sk\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/sk\/","logo":{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/skyplanner.ai\/sk\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/sk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/sk\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Ak potrebujete aktualizova\u0165 inform\u00e1cie o existuj\u00facom zamestnancovi:","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/sk\/wp-json\/wp\/v2\/docs\/56328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/sk\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/sk\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/sk\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/sk\/wp-json\/wp\/v2\/comments?post=56328"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/sk\/wp-json\/wp\/v2\/docs\/56328\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/sk\/wp-json\/wp\/v2\/media?parent=56328"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/sk\/wp-json\/wp\/v2\/doc_category?post=56328"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/sk\/wp-json\/wp\/v2\/doc_tag?post=56328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}