{"id":48806,"date":"2025-02-12T13:23:57","date_gmt":"2025-02-12T13:23:57","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/cum-sa-editati-o-schimbare-implicita\/"},"modified":"2025-10-07T08:22:56","modified_gmt":"2025-10-07T08:22:56","password":"","slug":"cum-sa-editati-o-schimbare-implicita","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/","title":{"rendered":"Cum s\u0103 edita\u021bi o schimbare implicit\u0103"},"content":{"rendered":"\n<p>Dac\u0103 dori\u021bi s\u0103 modifica\u021bi o schimbare implicit\u0103:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Merge\u021bi la<strong> Resurse<\/strong> \u0219i selecta\u021bi<strong> Ture implicite<\/strong>.<\/li>\n\n\n\n<li>\u00cen continuare, ve\u021bi vedea <strong>panoul Schimbare implicit\u0103<\/strong>, unde pute\u021bi vizualiza schimburile pe care le-a\u021bi creat.  <\/li>\n\n\n\n<li>Face\u021bi clic pe caseta de informa\u021bii pe care dori\u021bi s\u0103 o edita\u021bi.  <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"271\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-1024x271.png\" alt=\"\" class=\"wp-image-46835\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-1024x271.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-300x79.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-768x204.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-1536x407.png 1536w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-360x95.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46.png 1785w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>C\u00e2nd a\u021bi terminat, face\u021bi clic pe <strong>Salvare<\/strong>.  <\/li>\n<\/ul>\n\n<p>Acum, schimbul dvs. de lucru este actualizat.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dac\u0103 dori\u021bi s\u0103 modifica\u021bi o schimbare implicit\u0103: Acum, schimbul dvs. de lucru este actualizat.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[1852],"doc_tag":[],"class_list":["post-48806","docs","type-docs","status-publish","hentry","doc_category-schimburi-implicite"],"acf":[],"year_month":"2026-05","word_count":69,"total_views":"137","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/ro\/author\/bettina\/"},"doc_category_info":[{"term_name":"Schimburi implicite","term_url":"https:\/\/skyplanner.ai\/ro\/docs-category\/schimburi-implicite\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cum s\u0103 edita\u021bi o schimbare implicit\u0103 &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cum s\u0103 edita\u021bi o schimbare implicit\u0103\" \/>\n<meta property=\"og:description\" content=\"Dac\u0103 dori\u021bi s\u0103 modifica\u021bi o schimbare implicit\u0103: Acum, schimbul dvs. de lucru este actualizat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T08:22:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1785\" \/>\n\t<meta property=\"og:image:height\" content=\"473\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/\",\"url\":\"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/\",\"name\":\"Cum s\u0103 edita\u021bi o schimbare implicit\u0103 &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/ro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-1024x271.png\",\"datePublished\":\"2025-02-12T13:23:57+00:00\",\"dateModified\":\"2025-10-07T08:22:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/#primaryimage\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-1024x271.png\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-1024x271.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/ro\/prima-pagina\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/ro\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cum s\u0103 edita\u021bi o schimbare implicit\u0103\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/ro\/#website\",\"url\":\"https:\/\/skyplanner.ai\/ro\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/ro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/ro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/ro\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/ro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\/\/skyplanner.ai\/ro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/ro\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cum s\u0103 edita\u021bi o schimbare implicit\u0103 &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/","og_locale":"ro_RO","og_type":"article","og_title":"Cum s\u0103 edita\u021bi o schimbare implicit\u0103","og_description":"Dac\u0103 dori\u021bi s\u0103 modifica\u021bi o schimbare implicit\u0103: Acum, schimbul dvs. de lucru este actualizat.","og_url":"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T08:22:56+00:00","og_image":[{"width":1785,"height":473,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/","url":"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/","name":"Cum s\u0103 edita\u021bi o schimbare implicit\u0103 &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-1024x271.png","datePublished":"2025-02-12T13:23:57+00:00","dateModified":"2025-10-07T08:22:56+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-1024x271.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-46-1024x271.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/ro\/docs\/cum-sa-editati-o-schimbare-implicita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/ro\/prima-pagina\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/ro\/docs\/"},{"@type":"ListItem","position":3,"name":"Cum s\u0103 edita\u021bi o schimbare implicit\u0103"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/ro\/#website","url":"https:\/\/skyplanner.ai\/ro\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/ro\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/ro\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/skyplanner.ai\/ro\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/ro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/ro\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Dac\u0103 dori\u021bi s\u0103 modifica\u021bi o schimbare implicit\u0103: Acum, schimbul dvs. de lucru este actualizat.","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/ro\/wp-json\/wp\/v2\/docs\/48806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/ro\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/ro\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/ro\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/ro\/wp-json\/wp\/v2\/comments?post=48806"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/ro\/wp-json\/wp\/v2\/docs\/48806\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/ro\/wp-json\/wp\/v2\/media?parent=48806"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/ro\/wp-json\/wp\/v2\/doc_category?post=48806"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/ro\/wp-json\/wp\/v2\/doc_tag?post=48806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}