{"id":79288,"date":"2025-05-08T09:14:44","date_gmt":"2025-05-08T09:14:44","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/como-adicionar-uma-propriedade-a-um-produto\/"},"modified":"2025-10-08T07:44:15","modified_gmt":"2025-10-08T07:44:15","password":"","slug":"como-adicionar-uma-propriedade-a-um-produto","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/","title":{"rendered":"Como adicionar uma propriedade a um produto"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Similar Jobs in Succession\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/rW8g5D3ALs4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<p><strong>As propriedades<\/strong> s\u00e3o uma funcionalidade do SkyPlanner que te permite categorizar produtos com base em carater\u00edsticas partilhadas.  <\/p>\n\n<p>Podes associar uma propriedade espec\u00edfica a esta\u00e7\u00f5es de trabalho espec\u00edficas e, se seleccionares a op\u00e7\u00e3o<strong>&#8220;Allow similarity<\/strong>&#8221; (<strong>Permitir semelhan\u00e7a<\/strong>), a SkyPlanner agrupar\u00e1 consecutivamente as encomendas que partilham esta propriedade, desde que tal n\u00e3o afecte as outras<strong> regras de Prioridades din\u00e2micas <\/strong>que definiste.<\/p>\n\n<p>O principal objetivo das Propriedades \u00e9 poupar tempo de configura\u00e7\u00e3o e aumentar o controlo sobre a gest\u00e3o de recursos, simplificando assim o planeamento da produ\u00e7\u00e3o.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Vai para o<\/strong> m\u00f3dulo <strong>Armaz\u00e9m<\/strong> e seleciona <strong>Produtos<\/strong>.<\/li>\n\n\n\n<li><strong>Encontra<\/strong> o produto ao qual queres adicionar uma propriedade e <strong>clica<\/strong> nele.<\/li>\n\n\n\n<li>No painel de gest\u00e3o do produto, acede ao separador <strong>Propriedades<\/strong>.<\/li>\n\n\n\n<li>Clica em <strong>Gerir propriedades<\/strong> no lado esquerdo.<\/li>\n\n\n\n<li>Abre-se uma nova janela &#8211; clica em <strong>+ Adicionar propriedade<\/strong>.<\/li>\n\n\n\n<li>Na janela pop-up, introduz um <strong>nome<\/strong> para a propriedade. Este deve representar uma categoria que pretendes que produtos espec\u00edficos partilhem, como <g id=\"gid_1\">Mat\u00e9ria-prima<\/g>, <g id=\"gid_2\">Dimens\u00f5es<\/g>, <g id=\"gid_3\">Cor<\/g>. Quando tiveres terminado, clica em <strong>OK<\/strong> e depois em <strong>Fechar<\/strong>.  <\/li>\n\n\n\n<li>De volta \u00e0 vista do produto, clica no bot\u00e3o azul<strong> + Adicionar propriedade<\/strong>, \u00e0 direita.<\/li>\n\n\n\n<li>No menu pendente, seleciona a propriedade que acabaste de criar.<\/li>\n\n\n\n<li>Introduz um <strong>valor<\/strong> para esta propriedade &#8211; este valor ser\u00e1 utilizado para agrupar trabalhos.<\/li>\n<\/ul>\n\n<p><strong>Exemplifica<\/strong>: Se a propriedade for <strong>Cor<\/strong>, os valores podem ser <strong>Vermelho<\/strong>, <strong>Azul<\/strong> ou <strong>Verde<\/strong>.<\/p>\n\n<p>Nota: Lembra-te que o produto tem de ter um atributo relacionado com o produto.  <\/p>\n\n<p>Quando tiveres adicionado um valor, clica em <strong>Guardar propriedades<\/strong>.<\/p>\n\n<p>Agora j\u00e1 adicionaste uma propriedade a um produto!<\/p>\n\n<p><a href=\"https:\/\/skyplanner.ai\/docs\/how-to-make-a-workstation-consider-a-property-for-scheduling\/\">Aprende a fazer com que um posto de trabalho tenha em conta uma propriedade<\/a><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As propriedades s\u00e3o uma funcionalidade do SkyPlanner que te permite categorizar produtos com base em carater\u00edsticas partilhadas. Podes associar uma propriedade espec\u00edfica a esta\u00e7\u00f5es de trabalho espec\u00edficas e, se seleccionares a op\u00e7\u00e3o&#8220;Allow similarity&#8221; (Permitir semelhan\u00e7a), a SkyPlanner agrupar\u00e1 consecutivamente as encomendas que partilham esta propriedade, desde que tal n\u00e3o afecte as outras regras de Prioridades &#8230; <a title=\"Como adicionar uma propriedade a um produto\" class=\"read-more\" href=\"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/\" aria-label=\"Leia mais sobre Como adicionar uma propriedade a um produto\">Ler mais<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[2059],"doc_tag":[],"class_list":["post-79288","docs","type-docs","status-publish","hentry","doc_category-produtos-pt-pt"],"acf":[],"year_month":"2026-05","word_count":287,"total_views":"139","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/pt-pt\/author\/bettina\/"},"doc_category_info":[{"term_name":"Produtos","term_url":"https:\/\/skyplanner.ai\/pt-pt\/docs-category\/produtos-pt-pt\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Como adicionar uma propriedade a um produto &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como adicionar uma propriedade a um produto\" \/>\n<meta property=\"og:description\" content=\"As propriedades s\u00e3o uma funcionalidade do SkyPlanner que te permite categorizar produtos com base em carater\u00edsticas partilhadas. Podes associar uma propriedade espec\u00edfica a esta\u00e7\u00f5es de trabalho espec\u00edficas e, se seleccionares a op\u00e7\u00e3o&#8220;Allow similarity&#8221; (Permitir semelhan\u00e7a), a SkyPlanner agrupar\u00e1 consecutivamente as encomendas que partilham esta propriedade, desde que tal n\u00e3o afecte as outras regras de Prioridades ... Ler mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T07:44:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/\",\"url\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/\",\"name\":\"Como adicionar uma propriedade a um produto &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#website\"},\"datePublished\":\"2025-05-08T09:14:44+00:00\",\"dateModified\":\"2025-10-08T07:44:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/pt-pt\/pagina-inicial\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como adicionar uma propriedade a um produto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#website\",\"url\":\"https:\/\/skyplanner.ai\/pt-pt\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/pt-pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Como adicionar uma propriedade a um produto &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/","og_locale":"pt_PT","og_type":"article","og_title":"Como adicionar uma propriedade a um produto","og_description":"As propriedades s\u00e3o uma funcionalidade do SkyPlanner que te permite categorizar produtos com base em carater\u00edsticas partilhadas. Podes associar uma propriedade espec\u00edfica a esta\u00e7\u00f5es de trabalho espec\u00edficas e, se seleccionares a op\u00e7\u00e3o&#8220;Allow similarity&#8221; (Permitir semelhan\u00e7a), a SkyPlanner agrupar\u00e1 consecutivamente as encomendas que partilham esta propriedade, desde que tal n\u00e3o afecte as outras regras de Prioridades ... Ler mais","og_url":"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-08T07:44:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/","url":"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/","name":"Como adicionar uma propriedade a um produto &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/#website"},"datePublished":"2025-05-08T09:14:44+00:00","dateModified":"2025-10-08T07:44:15+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/como-adicionar-uma-propriedade-a-um-produto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/pt-pt\/pagina-inicial\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/pt-pt\/docs\/"},{"@type":"ListItem","position":3,"name":"Como adicionar uma propriedade a um produto"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/pt-pt\/#website","url":"https:\/\/skyplanner.ai\/pt-pt\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/pt-pt\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/skyplanner.ai\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/pt-pt\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"As propriedades s\u00e3o uma funcionalidade do SkyPlanner que te permite categorizar produtos com base em carater\u00edsticas partilhadas. Podes associar uma propriedade espec\u00edfica a esta\u00e7\u00f5es de trabalho espec\u00edficas e, se seleccionares a op\u00e7\u00e3o&#8220;Allow similarity&#8221; (Permitir semelhan\u00e7a), a SkyPlanner agrupar\u00e1 consecutivamente as encomendas que partilham esta propriedade, desde que tal n\u00e3o afecte as outras regras de Prioridades&hellip;","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/docs\/79288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/comments?post=79288"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/docs\/79288\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/media?parent=79288"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/doc_category?post=79288"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/doc_tag?post=79288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}