{"id":79275,"date":"2025-05-02T05:46:01","date_gmt":"2025-05-02T05:46:01","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/"},"modified":"2025-10-08T07:42:59","modified_gmt":"2025-10-08T07:42:59","password":"","slug":"excepcoes-ao-posto-de-trabalho-pessoa","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/","title":{"rendered":"Excep\u00e7\u00f5es ao posto de trabalho\/pessoa"},"content":{"rendered":"\n<p>Aqui aprender\u00e1s a criar, atualizar e eliminar excep\u00e7\u00f5es de postos de trabalho e de pessoas. As excep\u00e7\u00f5es s\u00e3o pausas nas capacidades de um posto de trabalho ou nos turnos de uma pessoa. Uma exce\u00e7\u00e3o de m\u00e1quina pode ser, por exemplo, uma interrup\u00e7\u00e3o de servi\u00e7o ou de manuten\u00e7\u00e3o e uma exce\u00e7\u00e3o de pessoa pode ser um feriado, uma baixa por doen\u00e7a ou umas f\u00e9rias.  <\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-workstation-exceptions\">Excep\u00e7\u00f5es \u00e0 esta\u00e7\u00e3o de trabalho<\/h4>\n\n<p>As excep\u00e7\u00f5es de esta\u00e7\u00e3o de trabalho podem ser acedidas a partir do ponto final <mark style=\"background-color:var(--contrast-3)\" class=\"has-inline-color\">\/workstation-exceptions<\/mark>.<\/p>\n\n<p>As excep\u00e7\u00f5es de pessoas podem ser acedidas a partir do ponto final <mark style=\"background-color:var(--contrast-3)\" class=\"has-inline-color\">\/person-exceptions<\/mark>.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-fetching-exceptions\">Obten\u00e7\u00e3o de excep\u00e7\u00f5es<\/h4>\n\n<p>Vai buscar as excep\u00e7\u00f5es existentes enviando pedidos GET como este:<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"622\" height=\"745\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-2.png\" alt=\"\" class=\"wp-image-67290\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-2.png 622w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-2-250x300.png 250w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-2-360x431.png 360w\" sizes=\"(max-width: 622px) 100vw, 622px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 1.<\/strong>  Obter as excep\u00e7\u00f5es de uma pessoa<\/figcaption><\/figure>\n\n<p>Podes obter as excep\u00e7\u00f5es da esta\u00e7\u00e3o de trabalho por <strong>tipo<\/strong>, <strong>workstation_id<\/strong>, <strong>external_id<\/strong> ou condi\u00e7\u00f5es <strong>modificadas<\/strong>.<\/p>\n\n<p>Podes ir buscar excep\u00e7\u00f5es de pessoas por <strong>tipo<\/strong>, <strong>person_id<\/strong> ou condi\u00e7\u00f5es <strong>modificadas<\/strong> <\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-creating-an-exception\">Criar uma exce\u00e7\u00e3o<\/h4>\n\n<p>Podes criar uma exce\u00e7\u00e3o de esta\u00e7\u00e3o de trabalho enviando um pedido POST como este:<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"622\" height=\"598\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/image-5.png\" alt=\"\" class=\"wp-image-67174\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/image-5.png 622w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/image-5-300x288.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/image-5-360x346.png 360w\" sizes=\"(max-width: 622px) 100vw, 622px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 2.<\/strong>  Criar uma exce\u00e7\u00e3o de esta\u00e7\u00e3o de trabalho<\/figcaption><\/figure>\n\n<p>Para especificar a esta\u00e7\u00e3o de trabalho para a qual a exce\u00e7\u00e3o est\u00e1 programada, utiliza o campo <strong>workstation_id<\/strong>.<\/p>\n\n<p>Os <strong>tipos<\/strong> de excep\u00e7\u00f5es permitidos para as esta\u00e7\u00f5es de trabalho s\u00e3o: <strong>Manuten\u00e7\u00e3o<\/strong>, <strong>Limpeza<\/strong> e<strong> Desloca\u00e7\u00e3o\/Organiza\u00e7\u00e3o<\/strong>.<\/p>\n\n<p>Nota que tamb\u00e9m podes fornecer um <strong>external_id<\/strong> para uma exce\u00e7\u00e3o de esta\u00e7\u00e3o de trabalho.<\/p>\n\n<p>Para criar uma exce\u00e7\u00e3o de pessoa, envia um pedido POST como este:<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"616\" height=\"580\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image.png\" alt=\"\" class=\"wp-image-67232\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image.png 616w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-300x282.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-360x339.png 360w\" sizes=\"(max-width: 616px) 100vw, 616px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 3.<\/strong>  Criar uma exce\u00e7\u00e3o de pessoa<\/figcaption><\/figure>\n\n<p>Para especificar para que pessoa \u00e9 criada a exce\u00e7\u00e3o, tens de utilizar o <strong>person_id<\/strong>.<\/p>\n\n<p>Os <strong>tipos<\/strong> de excep\u00e7\u00f5es permitidos para as pessoas s\u00e3o: <strong>F\u00e9rias, licen\u00e7a por doen\u00e7a, licen\u00e7a flex\u00edvel e licen\u00e7a sem vencimento<\/strong>.<\/p>\n\n<h4 class=\"wp-block-heading\" id=\"h-updating-an-exception\">Atualizar uma exce\u00e7\u00e3o<\/h4>\n\n<p>Para atualizar uma exce\u00e7\u00e3o, tens de utilizar o <strong>ID da exce\u00e7\u00e3o<\/strong> que podes obter enviando pedidos GET ou a partir da mensagem de resposta quando crias essa exce\u00e7\u00e3o.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"627\" height=\"548\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-1.png\" alt=\"\" class=\"wp-image-67261\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-1.png 627w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-1-300x262.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-1-360x315.png 360w\" sizes=\"(max-width: 627px) 100vw, 627px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 4.<\/strong>  Atualizar uma exce\u00e7\u00e3o<\/figcaption><\/figure>\n\n<h4 class=\"wp-block-heading\" id=\"h-deleting-exceptions\">Eliminar excep\u00e7\u00f5es<\/h4>\n\n<p>A elimina\u00e7\u00e3o de excep\u00e7\u00f5es da esta\u00e7\u00e3o de trabalho pode ser feita fornecendo <strong>IDs de exce\u00e7\u00e3o internos<\/strong>, <strong>external_ids <\/strong>ou<strong> workstation_ids<\/strong>.<\/p>\n\n<p>A elimina\u00e7\u00e3o de excep\u00e7\u00f5es de pessoas pode ser feita fornecendo <strong>ids de exce\u00e7\u00e3o internos<\/strong> ou <strong>person_ids<\/strong>.<\/p>\n\n<p>Podem ser eliminados v\u00e1rios conjuntos de excep\u00e7\u00f5es num \u00fanico pedido, fornecendo os ids numa matriz:<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"627\" height=\"391\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-4.png\" alt=\"\" class=\"wp-image-67348\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-4.png 627w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-4-300x187.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-4-360x224.png 360w\" sizes=\"(max-width: 627px) 100vw, 627px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 5.<\/strong>  Eliminar excep\u00e7\u00f5es da esta\u00e7\u00e3o de trabalho<\/figcaption><\/figure>\n\n<p>A mensagem de resposta de um pedido DELETE indica-te quantas excep\u00e7\u00f5es foram eliminadas.<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aqui aprender\u00e1s a criar, atualizar e eliminar excep\u00e7\u00f5es de postos de trabalho e de pessoas. As excep\u00e7\u00f5es s\u00e3o pausas nas capacidades de um posto de trabalho ou nos turnos de uma pessoa. Uma exce\u00e7\u00e3o de m\u00e1quina pode ser, por exemplo, uma interrup\u00e7\u00e3o de servi\u00e7o ou de manuten\u00e7\u00e3o e uma exce\u00e7\u00e3o de pessoa pode ser um &#8230; <a title=\"Excep\u00e7\u00f5es ao posto de trabalho\/pessoa\" class=\"read-more\" href=\"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/\" aria-label=\"Leia mais sobre Excep\u00e7\u00f5es ao posto de trabalho\/pessoa\">Ler mais<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[663],"doc_tag":[664,1533],"class_list":["post-79275","docs","type-docs","status-publish","hentry","doc_category-integracoes-pt-pt","doc_tag-api-pt-pt","doc_tag-integracao"],"acf":[],"year_month":"2026-09","word_count":451,"total_views":"176","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Sami","author_nicename":"sami","author_url":"https:\/\/skyplanner.ai\/pt-pt\/author\/sami\/"},"doc_category_info":[{"term_name":"Integra\u00e7\u00f5es","term_url":"https:\/\/skyplanner.ai\/pt-pt\/docs-category\/integracoes-pt-pt\/"}],"doc_tag_info":[{"term_name":"API","term_url":"https:\/\/skyplanner.ai\/pt-pt\/docs-tag\/api-pt-pt\/"},{"term_name":"Integra\u00e7\u00e3o","term_url":"https:\/\/skyplanner.ai\/pt-pt\/docs-tag\/integracao\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Excep\u00e7\u00f5es ao posto de trabalho\/pessoa &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Excep\u00e7\u00f5es ao posto de trabalho\/pessoa\" \/>\n<meta property=\"og:description\" content=\"Aqui aprender\u00e1s a criar, atualizar e eliminar excep\u00e7\u00f5es de postos de trabalho e de pessoas. As excep\u00e7\u00f5es s\u00e3o pausas nas capacidades de um posto de trabalho ou nos turnos de uma pessoa. Uma exce\u00e7\u00e3o de m\u00e1quina pode ser, por exemplo, uma interrup\u00e7\u00e3o de servi\u00e7o ou de manuten\u00e7\u00e3o e uma exce\u00e7\u00e3o de pessoa pode ser um ... Ler mais\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T07:42:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"622\" \/>\n\t<meta property=\"og:image:height\" content=\"745\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/docs\\\/excepcoes-ao-posto-de-trabalho-pessoa\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/docs\\\/excepcoes-ao-posto-de-trabalho-pessoa\\\/\",\"name\":\"Excep\u00e7\u00f5es ao posto de trabalho\\\/pessoa &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/docs\\\/excepcoes-ao-posto-de-trabalho-pessoa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/docs\\\/excepcoes-ao-posto-de-trabalho-pessoa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image-2.png\",\"datePublished\":\"2025-05-02T05:46:01+00:00\",\"dateModified\":\"2025-10-08T07:42:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/docs\\\/excepcoes-ao-posto-de-trabalho-pessoa\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/docs\\\/excepcoes-ao-posto-de-trabalho-pessoa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/docs\\\/excepcoes-ao-posto-de-trabalho-pessoa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image-2.png\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image-2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/docs\\\/excepcoes-ao-posto-de-trabalho-pessoa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/docs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Excep\u00e7\u00f5es ao posto de trabalho\\\/pessoa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@SkyPlannerAPS\",\"https:\\\/\\\/www.capterra.com\\\/p\\\/265911\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.trustradius.com\\\/products\\\/skyplanner-aps\\\/reviews\",\"https:\\\/\\\/www.saasworthy.com\\\/product\\\/skyplanner-aps\",\"https:\\\/\\\/sourceforge.net\\\/software\\\/product\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.g2.com\\\/products\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.getapp.com\\\/project-management-planning-software\\\/a\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.softwareadvice.com\\\/cmms\\\/skyplanner-aps-profile\\\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/trial\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Excep\u00e7\u00f5es ao posto de trabalho\/pessoa &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/","og_locale":"pt_PT","og_type":"article","og_title":"Excep\u00e7\u00f5es ao posto de trabalho\/pessoa","og_description":"Aqui aprender\u00e1s a criar, atualizar e eliminar excep\u00e7\u00f5es de postos de trabalho e de pessoas. As excep\u00e7\u00f5es s\u00e3o pausas nas capacidades de um posto de trabalho ou nos turnos de uma pessoa. Uma exce\u00e7\u00e3o de m\u00e1quina pode ser, por exemplo, uma interrup\u00e7\u00e3o de servi\u00e7o ou de manuten\u00e7\u00e3o e uma exce\u00e7\u00e3o de pessoa pode ser um ... Ler mais","og_url":"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-08T07:42:59+00:00","og_image":[{"width":622,"height":745,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/","url":"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/","name":"Excep\u00e7\u00f5es ao posto de trabalho\/pessoa &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-2.png","datePublished":"2025-05-02T05:46:01+00:00","dateModified":"2025-10-08T07:42:59+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-2.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/05\/image-2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/excepcoes-ao-posto-de-trabalho-pessoa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/pt-pt\/docs\/"},{"@type":"ListItem","position":3,"name":"Excep\u00e7\u00f5es ao posto de trabalho\/pessoa"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/pt-pt\/#website","url":"https:\/\/skyplanner.ai\/pt-pt\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/pt-pt\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/skyplanner.ai\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"Sami","author_link":"https:\/\/skyplanner.ai\/pt-pt\/author\/sami\/"},"uagb_comment_info":0,"uagb_excerpt":"Aqui aprender\u00e1s a criar, atualizar e eliminar excep\u00e7\u00f5es de postos de trabalho e de pessoas. As excep\u00e7\u00f5es s\u00e3o pausas nas capacidades de um posto de trabalho ou nos turnos de uma pessoa. Uma exce\u00e7\u00e3o de m\u00e1quina pode ser, por exemplo, uma interrup\u00e7\u00e3o de servi\u00e7o ou de manuten\u00e7\u00e3o e uma exce\u00e7\u00e3o de pessoa pode ser um&hellip;","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/docs\/79275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/comments?post=79275"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/docs\/79275\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/media?parent=79275"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/doc_category?post=79275"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/doc_tag?post=79275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}