{"id":56271,"date":"2025-02-20T08:16:17","date_gmt":"2025-02-20T08:16:17","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/programacao-do-pessoal\/"},"modified":"2025-10-07T10:56:44","modified_gmt":"2025-10-07T10:56:44","password":"","slug":"programacao-do-pessoal","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/","title":{"rendered":"Programa\u00e7\u00e3o do pessoal"},"content":{"rendered":"\n<p>Na Programa\u00e7\u00e3o de pessoal, podes ver o turno de um trabalhador espec\u00edfico.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Vai a <strong>Recursos<\/strong> e seleciona <strong>Programa\u00e7\u00e3o de pessoal<\/strong>.<\/li>\n\n\n\n<li>Aparece o painel <strong>Programa\u00e7\u00e3o orientada para os empregados<\/strong>. No canto superior esquerdo, clica na caixa para ver a lista de empregados ou escreve o nome do trabalhador cujo hor\u00e1rio de turnos pretendes ver. Neste exemplo, seleciona Henry Miller.    <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"255\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-1024x255.png\" alt=\"\" class=\"wp-image-53421\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-1024x255.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-300x75.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-768x192.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-1536x383.png 1536w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-360x90.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152.png 1908w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<p>Agora podes ver os turnos que esta pessoa vai fazer durante a semana.  <\/p>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"251\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-154-1024x251.png\" alt=\"\" class=\"wp-image-53479\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-154-1024x251.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-154-300x74.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-154-768x189.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-154-1536x377.png 1536w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-154-360x88.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-154.png 1935w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na Programa\u00e7\u00e3o de pessoal, podes ver o turno de um trabalhador espec\u00edfico. Agora podes ver os turnos que esta pessoa vai fazer durante a semana.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[2301],"doc_tag":[],"class_list":["post-56271","docs","type-docs","status-publish","hentry","doc_category-programacao-do-pessoal"],"acf":[],"year_month":"2026-05","word_count":76,"total_views":"124","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/pt-pt\/author\/bettina\/"},"doc_category_info":[{"term_name":"Programa\u00e7\u00e3o do pessoal","term_url":"https:\/\/skyplanner.ai\/pt-pt\/docs-category\/programacao-do-pessoal\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Programa\u00e7\u00e3o do pessoal &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programa\u00e7\u00e3o do pessoal\" \/>\n<meta property=\"og:description\" content=\"Na Programa\u00e7\u00e3o de pessoal, podes ver o turno de um trabalhador espec\u00edfico. Agora podes ver os turnos que esta pessoa vai fazer durante a semana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T10:56:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1908\" \/>\n\t<meta property=\"og:image:height\" content=\"476\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/\",\"url\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/\",\"name\":\"Programa\u00e7\u00e3o do pessoal &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-1024x255.png\",\"datePublished\":\"2025-02-20T08:16:17+00:00\",\"dateModified\":\"2025-10-07T10:56:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/#primaryimage\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-1024x255.png\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-1024x255.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/pt-pt\/pagina-inicial\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/pt-pt\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Programa\u00e7\u00e3o do pessoal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#website\",\"url\":\"https:\/\/skyplanner.ai\/pt-pt\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/pt-pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Programa\u00e7\u00e3o do pessoal &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/","og_locale":"pt_PT","og_type":"article","og_title":"Programa\u00e7\u00e3o do pessoal","og_description":"Na Programa\u00e7\u00e3o de pessoal, podes ver o turno de um trabalhador espec\u00edfico. Agora podes ver os turnos que esta pessoa vai fazer durante a semana.","og_url":"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T10:56:44+00:00","og_image":[{"width":1908,"height":476,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/","url":"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/","name":"Programa\u00e7\u00e3o do pessoal &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-1024x255.png","datePublished":"2025-02-20T08:16:17+00:00","dateModified":"2025-10-07T10:56:44+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-1024x255.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-152-1024x255.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/pt-pt\/docs\/programacao-do-pessoal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/pt-pt\/pagina-inicial\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/pt-pt\/docs\/"},{"@type":"ListItem","position":3,"name":"Programa\u00e7\u00e3o do pessoal"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/pt-pt\/#website","url":"https:\/\/skyplanner.ai\/pt-pt\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/pt-pt\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/skyplanner.ai\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/pt-pt\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Na Programa\u00e7\u00e3o de pessoal, podes ver o turno de um trabalhador espec\u00edfico. Agora podes ver os turnos que esta pessoa vai fazer durante a semana.","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/docs\/56271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/comments?post=56271"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/docs\/56271\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/media?parent=56271"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/doc_category?post=56271"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-pt\/wp-json\/wp\/v2\/doc_tag?post=56271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}