{"id":57857,"date":"2025-02-20T07:57:15","date_gmt":"2025-02-20T07:57:15","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/como-adicionar-uma-nova-etapa-de-processo\/"},"modified":"2025-12-09T08:55:58","modified_gmt":"2025-12-09T08:55:58","password":"","slug":"como-adicionar-uma-nova-etapa-de-processo","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/","title":{"rendered":"Como adicionar uma nova etapa de processo"},"content":{"rendered":"\n<p>Se quiseres criar uma nova etapa de processo:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Vai para<strong> Ordens<\/strong> e seleciona <strong>Etapas do processo<\/strong>.<\/li>\n<\/ul>\n\n<div class=\"wp-block-uagb-image uagb-block-dbefdbfd wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel-1024x243.webp ,https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel.webp 780w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel-1024x243.webp\" alt=\"\" class=\"uag-image-76859\" width=\"1893\" height=\"450\" title=\"Painel de etapas do processo\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Em seguida, ver\u00e1s o <strong>painel Etapas do processo<\/strong>. Encontrar\u00e1s aqui todos os passos do processo que a tua empresa pode elaborar. No canto superior direito, clica em <strong>+<\/strong> <strong>Adicionar etapa do processo<\/strong>.  <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"184\" height=\"46\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-129.png\" alt=\"\" class=\"wp-image-52730\"\/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Aparecer\u00e1 uma janela com op\u00e7\u00f5es para definir esta nova configura\u00e7\u00e3o de etapa de processo. Escreve o nome, seleciona uma esta\u00e7\u00e3o de trabalho e outras informa\u00e7\u00f5es relevantes para esta nova etapa de processo. <\/li>\n<\/ul>\n\n<div class=\"wp-block-uagb-image uagb-block-84ba46f2 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/process-step-settings-1024x795.png ,https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/process-step-settings.png 780w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/process-step-settings.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/process-step-settings-1024x795.png\" alt=\"\" class=\"uag-image-76888\" width=\"1049\" height=\"814\" title=\"defini\u00e7\u00f5es das etapas do processo\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Por fim, clica em <strong>Guardar<\/strong>. A tua nova etapa de processo aparecer\u00e1 agora no painel.  <\/li>\n<\/ul>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se quiseres criar uma nova etapa de processo:<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[2258],"doc_tag":[],"class_list":["post-57857","docs","type-docs","status-publish","hentry","doc_category-etapas-do-processo-pt-br"],"acf":[],"year_month":"2026-05","word_count":100,"total_views":"131","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/pt-br\/author\/bettina\/"},"doc_category_info":[{"term_name":"Etapas do processo","term_url":"https:\/\/skyplanner.ai\/pt-br\/docs-category\/etapas-do-processo-pt-br\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Como adicionar uma nova etapa de processo &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como adicionar uma nova etapa de processo\" \/>\n<meta property=\"og:description\" content=\"Se quiseres criar uma nova etapa de processo:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-09T08:55:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel-1024x243.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/\",\"url\":\"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/\",\"name\":\"Como adicionar uma nova etapa de processo &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel-1024x243.webp\",\"datePublished\":\"2025-02-20T07:57:15+00:00\",\"dateModified\":\"2025-12-09T08:55:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/#primaryimage\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel-1024x243.webp\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel-1024x243.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/pt-br\/pagina-inicial\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/pt-br\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Como adicionar uma nova etapa de processo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/#website\",\"url\":\"https:\/\/skyplanner.ai\/pt-br\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Como adicionar uma nova etapa de processo &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/","og_locale":"pt_BR","og_type":"article","og_title":"Como adicionar uma nova etapa de processo","og_description":"Se quiseres criar uma nova etapa de processo:","og_url":"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/","og_site_name":"SkyPlanner","article_modified_time":"2025-12-09T08:55:58+00:00","og_image":[{"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel-1024x243.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/","url":"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/","name":"Como adicionar uma nova etapa de processo &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel-1024x243.webp","datePublished":"2025-02-20T07:57:15+00:00","dateModified":"2025-12-09T08:55:58+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel-1024x243.webp","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Process-step-panel-1024x243.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/pt-br\/docs\/como-adicionar-uma-nova-etapa-de-processo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/pt-br\/pagina-inicial\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/pt-br\/docs\/"},{"@type":"ListItem","position":3,"name":"Como adicionar uma nova etapa de processo"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/pt-br\/#website","url":"https:\/\/skyplanner.ai\/pt-br\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/pt-br\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/skyplanner.ai\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/pt-br\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Se quiseres criar uma nova etapa de processo:","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/pt-br\/wp-json\/wp\/v2\/docs\/57857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/pt-br\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/pt-br\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-br\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-br\/wp-json\/wp\/v2\/comments?post=57857"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/pt-br\/wp-json\/wp\/v2\/docs\/57857\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/pt-br\/wp-json\/wp\/v2\/media?parent=57857"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-br\/wp-json\/wp\/v2\/doc_category?post=57857"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/pt-br\/wp-json\/wp\/v2\/doc_tag?post=57857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}