{"id":79652,"date":"2025-04-30T08:26:08","date_gmt":"2025-04-30T08:26:08","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/come-cancellare-un-ordine-dacquisto\/"},"modified":"2025-10-08T08:16:21","modified_gmt":"2025-10-08T08:16:21","password":"","slug":"come-cancellare-un-ordine-dacquisto","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/","title":{"rendered":"Come cancellare un ordine d&#8217;acquisto"},"content":{"rendered":"\n<p>Puoi cancellare l&#8217;ordine d&#8217;acquisto modificando le informazioni, ma puoi farlo se non vuoi che questo ordine appaia nella tua lista:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Vai su <strong>Ordini<\/strong> e seleziona <strong>Ordini di acquisto<\/strong>.<\/li>\n\n\n\n<li>Una volta nel <strong>pannello Ordini di acquisto<\/strong>, clicca sull&#8217;<strong>icona con i tre puntini<\/strong> accanto all&#8217;acquisto che vuoi eliminare e seleziona Elimina.<\/li>\n\n\n\n<li>Verr\u00e0 visualizzata una finestra per confermare la tua scelta. Clicca su <strong>Elimina<\/strong>. <\/li>\n<\/ul>\n\n<p>Ora, questo ordine di acquisto non apparir\u00e0 nella tua lista.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"589\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1024x589.webp\" alt=\"\" class=\"wp-image-66841\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1024x589.webp 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-300x173.webp 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-768x442.webp 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1536x884.webp 1536w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-2048x1179.webp 2048w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-360x207.webp 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"425\" height=\"207\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-button.webp\" alt=\"\" class=\"wp-image-66870\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-button.webp 425w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-button-300x146.webp 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-button-360x175.webp 360w\" sizes=\"(max-width: 425px) 100vw, 425px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Puoi cancellare l&#8217;ordine d&#8217;acquisto modificando le informazioni, ma puoi farlo se non vuoi che questo ordine appaia nella tua lista: Ora, questo ordine di acquisto non apparir\u00e0 nella tua lista.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[2263],"doc_tag":[],"class_list":["post-79652","docs","type-docs","status-publish","hentry","doc_category-ordini-di-acquisto"],"acf":[],"year_month":"2026-09","word_count":71,"total_views":"189","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/it\/author\/bettina\/"},"doc_category_info":[{"term_name":"Ordini di acquisto","term_url":"https:\/\/skyplanner.ai\/it\/docs-category\/ordini-di-acquisto\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Come cancellare un ordine d&#039;acquisto &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come cancellare un ordine d&#039;acquisto\" \/>\n<meta property=\"og:description\" content=\"Puoi cancellare l&#8217;ordine d&#8217;acquisto modificando le informazioni, ma puoi farlo se non vuoi che questo ordine appaia nella tua lista: Ora, questo ordine di acquisto non apparir\u00e0 nella tua lista.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T08:16:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2078\" \/>\n\t<meta property=\"og:image:height\" content=\"1196\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/come-cancellare-un-ordine-dacquisto\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/come-cancellare-un-ordine-dacquisto\\\/\",\"name\":\"Come cancellare un ordine d'acquisto &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/come-cancellare-un-ordine-dacquisto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/come-cancellare-un-ordine-dacquisto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/delete-purchase-order-1024x589.webp\",\"datePublished\":\"2025-04-30T08:26:08+00:00\",\"dateModified\":\"2025-10-08T08:16:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/come-cancellare-un-ordine-dacquisto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/come-cancellare-un-ordine-dacquisto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/come-cancellare-un-ordine-dacquisto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/delete-purchase-order-1024x589.webp\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/delete-purchase-order-1024x589.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/come-cancellare-un-ordine-dacquisto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come cancellare un ordine d&#8217;acquisto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@SkyPlannerAPS\",\"https:\\\/\\\/www.capterra.com\\\/p\\\/265911\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.trustradius.com\\\/products\\\/skyplanner-aps\\\/reviews\",\"https:\\\/\\\/www.saasworthy.com\\\/product\\\/skyplanner-aps\",\"https:\\\/\\\/sourceforge.net\\\/software\\\/product\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.g2.com\\\/products\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.getapp.com\\\/project-management-planning-software\\\/a\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.softwareadvice.com\\\/cmms\\\/skyplanner-aps-profile\\\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/trial\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come cancellare un ordine d'acquisto &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/","og_locale":"it_IT","og_type":"article","og_title":"Come cancellare un ordine d'acquisto","og_description":"Puoi cancellare l&#8217;ordine d&#8217;acquisto modificando le informazioni, ma puoi farlo se non vuoi che questo ordine appaia nella tua lista: Ora, questo ordine di acquisto non apparir\u00e0 nella tua lista.","og_url":"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-08T08:16:21+00:00","og_image":[{"width":2078,"height":1196,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/","url":"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/","name":"Come cancellare un ordine d'acquisto &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1024x589.webp","datePublished":"2025-04-30T08:26:08+00:00","dateModified":"2025-10-08T08:16:21+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1024x589.webp","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1024x589.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/it\/docs\/come-cancellare-un-ordine-dacquisto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/it\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/it\/docs\/"},{"@type":"ListItem","position":3,"name":"Come cancellare un ordine d&#8217;acquisto"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/it\/#website","url":"https:\/\/skyplanner.ai\/it\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/it\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/it\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Puoi cancellare l&#8217;ordine d&#8217;acquisto modificando le informazioni, ma puoi farlo se non vuoi che questo ordine appaia nella tua lista: Ora, questo ordine di acquisto non apparir\u00e0 nella tua lista.","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs\/79652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/comments?post=79652"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs\/79652\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/media?parent=79652"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/doc_category?post=79652"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/doc_tag?post=79652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}