{"id":59000,"date":"2025-02-18T12:14:56","date_gmt":"2025-02-18T12:14:56","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/dipendenze-del-workstage\/"},"modified":"2025-10-07T09:54:40","modified_gmt":"2025-10-07T09:54:40","password":"","slug":"dipendenze-del-workstage","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/","title":{"rendered":"Dipendenze del workstage"},"content":{"rendered":"\n<p>Una fase del processo pu\u00f2 richiedere il completamento (o un certo grado di completamento) di una fase precedente prima di poter iniziare, anche se questo non \u00e8 sempre necessario.<\/p>\n\n<p><strong>SkyPlanner<\/strong> offre un&#8217;opzione personalizzabile, che consente alle aziende di specificare se esistono tali dipendenze tra le attivit\u00e0 lavorative interne. Questo permette di gestire il flusso di lavoro in base alle esigenze specifiche di ogni commessa. Quando \u00e8 attivata, mostra il Flusso di lavoro in linee rosse, come nell&#8217;immagine seguente.    <\/p>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"392\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-107-1024x392.png\" alt=\"\" class=\"wp-image-52068\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-107-1024x392.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-107-300x115.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-107-768x294.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-107-360x138.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-107.png 1429w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<p>Questa funzione si attiva automaticamente quando utilizzi la tua prova su Skyplanner.  <\/p>\n\n<p>Puoi trovare questa opzione qui:  <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Nella <strong>Timeline<\/strong> di <strong>GANTT<\/strong>, seleziona un lavoro qualsiasi e fai clic con il tasto destro del mouse su di esso.  <\/li>\n\n\n\n<li>Verr\u00e0 visualizzato un menu a tendina; seleziona <strong>Regole del lavoro<\/strong>.  <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"447\" height=\"438\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-108.png\" alt=\"\" class=\"wp-image-52097\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-108.png 447w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-108-300x294.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-108-360x353.png 360w\" sizes=\"(max-width: 447px) 100vw, 447px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Apparir\u00e0 una nuova finestra; vai su <strong>Regole globali<\/strong>.  <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"608\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-109-1024x608.png\" alt=\"\" class=\"wp-image-52126\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-109-1024x608.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-109-300x178.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-109-768x456.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-109-360x214.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-109.png 1330w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Cerca l&#8217;opzione <strong>Dipendenze di Workstage <\/strong>e seleziona la casella.  <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"871\" height=\"67\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-110.png\" alt=\"\" class=\"wp-image-52155\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-110.png 871w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-110-300x23.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-110-768x59.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-110-360x28.png 360w\" sizes=\"(max-width: 871px) 100vw, 871px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Infine, clicca su <strong>Salva<\/strong>.  <\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Una fase del processo pu\u00f2 richiedere il completamento (o un certo grado di completamento) di una fase precedente prima di poter iniziare, anche se questo non \u00e8 sempre necessario. SkyPlanner offre un&#8217;opzione personalizzabile, che consente alle aziende di specificare se esistono tali dipendenze tra le attivit\u00e0 lavorative interne. Questo permette di gestire il flusso di &#8230; <a title=\"Dipendenze del workstage\" class=\"read-more\" href=\"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/\" aria-label=\"Per saperne di pi\u00f9 su Dipendenze del workstage\">Leggi tutto<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[1872],"doc_tag":[1228,588],"class_list":["post-59000","docs","type-docs","status-publish","hentry","doc_category-uso-di-base","doc_tag-fasi-del-processo","doc_tag-grafico-di-gantt"],"acf":[],"year_month":"2026-09","word_count":144,"total_views":"206","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/it\/author\/bettina\/"},"doc_category_info":[{"term_name":"Uso di base","term_url":"https:\/\/skyplanner.ai\/it\/docs-category\/uso-di-base\/"}],"doc_tag_info":[{"term_name":"Fasi del processo","term_url":"https:\/\/skyplanner.ai\/it\/docs-tag\/fasi-del-processo\/"},{"term_name":"Grafico di Gantt","term_url":"https:\/\/skyplanner.ai\/it\/docs-tag\/grafico-di-gantt\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dipendenze del workstage &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dipendenze del workstage\" \/>\n<meta property=\"og:description\" content=\"Una fase del processo pu\u00f2 richiedere il completamento (o un certo grado di completamento) di una fase precedente prima di poter iniziare, anche se questo non \u00e8 sempre necessario. SkyPlanner offre un&#8217;opzione personalizzabile, che consente alle aziende di specificare se esistono tali dipendenze tra le attivit\u00e0 lavorative interne. Questo permette di gestire il flusso di ... Leggi tutto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T09:54:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-107.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1429\" \/>\n\t<meta property=\"og:image:height\" content=\"547\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/dipendenze-del-workstage\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/dipendenze-del-workstage\\\/\",\"name\":\"Dipendenze del workstage &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/dipendenze-del-workstage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/dipendenze-del-workstage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-107-1024x392.png\",\"datePublished\":\"2025-02-18T12:14:56+00:00\",\"dateModified\":\"2025-10-07T09:54:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/dipendenze-del-workstage\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/dipendenze-del-workstage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/dipendenze-del-workstage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-107-1024x392.png\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-107-1024x392.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/dipendenze-del-workstage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/docs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dipendenze del workstage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@SkyPlannerAPS\",\"https:\\\/\\\/www.capterra.com\\\/p\\\/265911\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.trustradius.com\\\/products\\\/skyplanner-aps\\\/reviews\",\"https:\\\/\\\/www.saasworthy.com\\\/product\\\/skyplanner-aps\",\"https:\\\/\\\/sourceforge.net\\\/software\\\/product\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.g2.com\\\/products\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.getapp.com\\\/project-management-planning-software\\\/a\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.softwareadvice.com\\\/cmms\\\/skyplanner-aps-profile\\\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/trial\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dipendenze del workstage &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/","og_locale":"it_IT","og_type":"article","og_title":"Dipendenze del workstage","og_description":"Una fase del processo pu\u00f2 richiedere il completamento (o un certo grado di completamento) di una fase precedente prima di poter iniziare, anche se questo non \u00e8 sempre necessario. SkyPlanner offre un&#8217;opzione personalizzabile, che consente alle aziende di specificare se esistono tali dipendenze tra le attivit\u00e0 lavorative interne. Questo permette di gestire il flusso di ... Leggi tutto","og_url":"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T09:54:40+00:00","og_image":[{"width":1429,"height":547,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-107.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/","url":"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/","name":"Dipendenze del workstage &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-107-1024x392.png","datePublished":"2025-02-18T12:14:56+00:00","dateModified":"2025-10-07T09:54:40+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-107-1024x392.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-107-1024x392.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/it\/docs\/dipendenze-del-workstage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/it\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/it\/docs\/"},{"@type":"ListItem","position":3,"name":"Dipendenze del workstage"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/it\/#website","url":"https:\/\/skyplanner.ai\/it\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/it\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/it\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Una fase del processo pu\u00f2 richiedere il completamento (o un certo grado di completamento) di una fase precedente prima di poter iniziare, anche se questo non \u00e8 sempre necessario. SkyPlanner offre un&#8217;opzione personalizzabile, che consente alle aziende di specificare se esistono tali dipendenze tra le attivit\u00e0 lavorative interne. Questo permette di gestire il flusso di&hellip;","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs\/59000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/comments?post=59000"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs\/59000\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/media?parent=59000"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/doc_category?post=59000"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/doc_tag?post=59000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}