{"id":56781,"date":"2025-02-20T08:06:33","date_gmt":"2025-02-20T08:06:33","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/come-creare-un-nuovo-ordine-2\/"},"modified":"2025-10-07T10:55:50","modified_gmt":"2025-10-07T10:55:50","password":"","slug":"come-creare-un-nuovo-ordine-2","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/","title":{"rendered":"Come creare un nuovo ordine"},"content":{"rendered":"\n<p><\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Creating Orders, Order items, and sending them to Production Scheduling\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/ZcYNKVf5-ws?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<p><\/p>\n\n<p>Dopo aver creato un nuovo ordine, vedrai un pulsante luminoso<strong> Crea un ordine in<\/strong> basso a sinistra. Cliccaci sopra. Si aprir\u00e0 una nuova finestra che ti permetter\u00e0 di gestire le impostazioni dell&#8217;articolo d&#8217;ordine.    <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Seleziona il prodotto da fabbricare. Puoi scoprire come aggiungere un prodotto<a href=\"https:\/\/www.youtube.com\/watch?v=WhrBh0Hm77w\"> qui<\/a>. <\/li>\n\n\n\n<li>Nel titolo, puoi dare un nome a questo ordine, ad esempio Prodotto 1 gennaio o Sedia Modello #45.<\/li>\n\n\n\n<li>Hai anche la possibilit\u00e0 di rendere questo ordine una <strong>prospettiva<\/strong>. Ci\u00f2 significa che puoi ottenere il piano di produzione di questo ordine per ottenere una data realistica in cui la tua azienda potr\u00e0 completarlo senza programmazione. Questa opzione viene generalmente utilizzata per supportare il team di vendita della tua azienda.    <\/li>\n\n\n\n<li>Puoi anche fare in modo che questo ordine abbia una dipendenza dai figli invertita.<\/li>\n\n\n\n<li>Puoi selezionare il giorno di inizio di questo nuovo lavoro cliccando sull&#8217;<strong> icona del calendario<\/strong> oppure saltare questa azione e permettere all&#8217;IA di scegliere il giorno migliore disponibile.  <\/li>\n\n\n\n<li>In Giorno di consegna, seleziona la data in cui vuoi che l&#8217;ordine sia finito e pronto per essere spedito.  <\/li>\n\n\n\n<li>Successivamente, scegli la <strong>Quantit\u00e0 di produzione<\/strong>. Questa \u00e8 la quantit\u00e0 effettiva che produrrai. Questa opzione \u00e8 utile se vuoi crearne un po&#8217; per conservarla in magazzino o per averne una scorta.    <\/li>\n\n\n\n<li>La quantit\u00e0 dell&#8217;ordine \u00e8 la quantit\u00e0 ordinata dal cliente.  <\/li>\n\n\n\n<li>Poi, puoi aggiungere altre informazioni come restrizioni, avvertimenti e altro ancora.  <\/li>\n\n\n\n<li>Puoi condividere ulteriori informazioni sull&#8217;articolo dell&#8217;ordine nelle opzioni di allegato, come ad esempio progetti o istruzioni.  <\/li>\n\n\n\n<li>Infine, clicca su<strong> Salva<\/strong>. Ora vedrai il nuovo pannello di modifica dell&#8217;ordine.   <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"488\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-1024x488.png\" alt=\"\" class=\"wp-image-53148\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-1024x488.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-300x143.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-768x366.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-1536x732.png 1536w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-360x172.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143.png 1824w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Alla tua destra vedrai le <strong>Fasi del processo<\/strong> per questo articolo. Puoi modificarle cliccando sull&#8217;<strong>icona dell&#8217;ingranaggio<\/strong> o eliminarle cliccando sull&#8217;<strong>icona<\/strong> del <strong>cestino<\/strong>.   <\/li>\n\n\n\n<li>Puoi cambiare l&#8217;ordine delle fasi tenendo premuto il tasto sinistro del mouse e spostando la fase selezionata. Puoi anche aggiungere una nuova fase del processo cliccando su <strong>Aggiungi fase del processo<\/strong> in basso. <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/cdn-assets.productfruits.com\/9fbd10e9-bb42-45dd-9a9a-ef7c32b55e50\" alt=\"\"\/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Noterai anche che il tuo nuovo ordine non \u00e8 ancora stato programmato. Clicca sul pulsante incandescente <strong>Programma la produzione<\/strong>.   <\/li>\n\n\n\n<li>Ora clicca sul pulsante <strong>Visualizza nella Timeline<\/strong>.  <\/li>\n\n\n\n<li>Verrai reindirizzato alla <strong>Timeline di GANTT<\/strong>. Qui vedrai il nuovo ordine in blu, il che significa che il lavoro \u00e8 ancora in bozza. Clicca su <strong>Accetta <\/strong>per programmare e far apparire questo lavoro nella timeline dei tuoi dipendenti, oppure su <strong>Scarta <\/strong> se non lo approvi.    <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"859\" height=\"478\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-144.png\" alt=\"\" class=\"wp-image-53177\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-144.png 859w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-144-300x167.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-144-768x427.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-144-360x200.png 360w\" sizes=\"(max-width: 859px) 100vw, 859px\" \/><\/figure>\n<\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo aver creato un nuovo ordine, vedrai un pulsante luminoso Crea un ordine in basso a sinistra. Cliccaci sopra. Si aprir\u00e0 una nuova finestra che ti permetter\u00e0 di gestire le impostazioni dell&#8217;articolo d&#8217;ordine.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[2157],"doc_tag":[588,692,797],"class_list":["post-56781","docs","type-docs","status-publish","hentry","doc_category-ordinare-articoli","doc_tag-grafico-di-gantt","doc_tag-phaser-it","doc_tag-video-introduttivo"],"acf":[],"year_month":"2026-05","word_count":380,"total_views":"153","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/it\/author\/bettina\/"},"doc_category_info":[{"term_name":"Ordinare articoli","term_url":"https:\/\/skyplanner.ai\/it\/docs-category\/ordinare-articoli\/"}],"doc_tag_info":[{"term_name":"Grafico di Gantt","term_url":"https:\/\/skyplanner.ai\/it\/docs-tag\/grafico-di-gantt\/"},{"term_name":"Phaser","term_url":"https:\/\/skyplanner.ai\/it\/docs-tag\/phaser-it\/"},{"term_name":"Video introduttivo","term_url":"https:\/\/skyplanner.ai\/it\/docs-tag\/video-introduttivo\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Come creare un nuovo ordine &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come creare un nuovo ordine\" \/>\n<meta property=\"og:description\" content=\"Dopo aver creato un nuovo ordine, vedrai un pulsante luminoso Crea un ordine in basso a sinistra. Cliccaci sopra. Si aprir\u00e0 una nuova finestra che ti permetter\u00e0 di gestire le impostazioni dell&#8217;articolo d&#8217;ordine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T10:55:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1824\" \/>\n\t<meta property=\"og:image:height\" content=\"869\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/\",\"url\":\"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/\",\"name\":\"Come creare un nuovo ordine &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-1024x488.png\",\"datePublished\":\"2025-02-20T08:06:33+00:00\",\"dateModified\":\"2025-10-07T10:55:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/#primaryimage\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-1024x488.png\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-1024x488.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/it\/pagina-iniziale\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/it\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come creare un nuovo ordine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/it\/#website\",\"url\":\"https:\/\/skyplanner.ai\/it\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/it\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come creare un nuovo ordine &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/","og_locale":"it_IT","og_type":"article","og_title":"Come creare un nuovo ordine","og_description":"Dopo aver creato un nuovo ordine, vedrai un pulsante luminoso Crea un ordine in basso a sinistra. Cliccaci sopra. Si aprir\u00e0 una nuova finestra che ti permetter\u00e0 di gestire le impostazioni dell&#8217;articolo d&#8217;ordine.","og_url":"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T10:55:50+00:00","og_image":[{"width":1824,"height":869,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/","url":"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/","name":"Come creare un nuovo ordine &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-1024x488.png","datePublished":"2025-02-20T08:06:33+00:00","dateModified":"2025-10-07T10:55:50+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-1024x488.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-143-1024x488.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/it\/docs\/come-creare-un-nuovo-ordine-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/it\/pagina-iniziale\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/it\/docs\/"},{"@type":"ListItem","position":3,"name":"Come creare un nuovo ordine"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/it\/#website","url":"https:\/\/skyplanner.ai\/it\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/it\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/it\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Dopo aver creato un nuovo ordine, vedrai un pulsante luminoso Crea un ordine in basso a sinistra. Cliccaci sopra. Si aprir\u00e0 una nuova finestra che ti permetter\u00e0 di gestire le impostazioni dell&#8217;articolo d&#8217;ordine.","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs\/56781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/comments?post=56781"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs\/56781\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/media?parent=56781"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/doc_category?post=56781"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/doc_tag?post=56781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}