{"id":49214,"date":"2025-02-13T07:27:54","date_gmt":"2025-02-13T07:27:54","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/come-eliminare-una-postazione-di-lavoro\/"},"modified":"2025-10-07T08:55:25","modified_gmt":"2025-10-07T08:55:25","password":"","slug":"come-eliminare-una-postazione-di-lavoro","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/","title":{"rendered":"Come eliminare una workstation"},"content":{"rendered":"\n<p>Se vuoi eliminare una workstation:<\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-video\"><video height=\"976\" style=\"aspect-ratio: 1908 \/ 976;\" width=\"1908\" controls=\"\" muted=\"\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Delete-a-workstation.mp4\"><\/video><\/figure>\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Andiamo in <strong>Risorse<\/strong> e selezioniamo <strong>Postazioni di lavoro<\/strong>. Il software ti porter\u00e0 a una pagina contenente tutte le postazioni di lavoro esistenti.   <\/li>\n\n\n\n<li>Cerca la workstation che vuoi modificare e seleziona l&#8217;<strong>icona <\/strong> <strong>rossa<\/strong> del <strong>cestino <\/strong>alla sua destra.<\/li>\n\n\n\n<li>SkyPlanner ti chieder\u00e0 se sei sicuro di eseguire questa azione. Clicca su <strong>Ok<\/strong>. <\/li>\n<\/ul>\n\n<p>La tua stazione di lavoro \u00e8 stata eliminata. Non la vedrai pi\u00f9 nel pannello Workstation. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se vuoi eliminare una workstation: La tua stazione di lavoro \u00e8 stata eliminata. Non la vedrai pi\u00f9 nel pannello Workstation.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[1901],"doc_tag":[],"class_list":["post-49214","docs","type-docs","status-publish","hentry","doc_category-postazioni-di-lavoro"],"acf":[],"year_month":"2026-05","word_count":69,"total_views":"173","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/it\/author\/bettina\/"},"doc_category_info":[{"term_name":"Postazioni di lavoro","term_url":"https:\/\/skyplanner.ai\/it\/docs-category\/postazioni-di-lavoro\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Come eliminare una workstation &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come eliminare una workstation\" \/>\n<meta property=\"og:description\" content=\"Se vuoi eliminare una workstation: La tua stazione di lavoro \u00e8 stata eliminata. Non la vedrai pi\u00f9 nel pannello Workstation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T08:55:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/\",\"url\":\"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/\",\"name\":\"Come eliminare una workstation &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/it\/#website\"},\"datePublished\":\"2025-02-13T07:27:54+00:00\",\"dateModified\":\"2025-10-07T08:55:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/it\/pagina-iniziale\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/it\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Come eliminare una workstation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/it\/#website\",\"url\":\"https:\/\/skyplanner.ai\/it\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/it\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Come eliminare una workstation &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/","og_locale":"it_IT","og_type":"article","og_title":"Come eliminare una workstation","og_description":"Se vuoi eliminare una workstation: La tua stazione di lavoro \u00e8 stata eliminata. Non la vedrai pi\u00f9 nel pannello Workstation.","og_url":"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T08:55:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/","url":"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/","name":"Come eliminare una workstation &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/it\/#website"},"datePublished":"2025-02-13T07:27:54+00:00","dateModified":"2025-10-07T08:55:25+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/it\/docs\/come-eliminare-una-postazione-di-lavoro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/it\/pagina-iniziale\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/it\/docs\/"},{"@type":"ListItem","position":3,"name":"Come eliminare una workstation"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/it\/#website","url":"https:\/\/skyplanner.ai\/it\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/it\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/it\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Se vuoi eliminare una workstation: La tua stazione di lavoro \u00e8 stata eliminata. Non la vedrai pi\u00f9 nel pannello Workstation.","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs\/49214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/comments?post=49214"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/docs\/49214\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/media?parent=49214"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/doc_category?post=49214"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/it\/wp-json\/wp\/v2\/doc_tag?post=49214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}