{"id":79656,"date":"2025-04-30T08:26:08","date_gmt":"2025-04-30T08:26:08","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/cara-menghapus-pesanan-pembelian\/"},"modified":"2025-10-08T08:16:24","modified_gmt":"2025-10-08T08:16:24","password":"","slug":"cara-menghapus-pesanan-pembelian","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/","title":{"rendered":"Cara menghapus pesanan Pembelian"},"content":{"rendered":"\n<p>Anda dapat membatalkan pesanan pembelian dengan mengedit informasi, tetapi Anda dapat melakukannya jika Anda tidak ingin pesanan ini muncul di daftar Anda:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Buka <strong>Pesanan<\/strong> dan pilih <strong>Pesanan pembelian<\/strong>.<\/li>\n\n\n\n<li>Setelah berada di <strong>panel Pesanan pembelian<\/strong>, klik <strong>ikon Tiga titik<\/strong> di sebelah pembelian yang ingin Anda hapus dan pilih hapus.<\/li>\n\n\n\n<li>Sebuah jendela akan muncul untuk mengonfirmasi pilihan Anda. Klik <strong>Hapus<\/strong>. <\/li>\n<\/ul>\n\n<p>Sekarang, pesanan pembelian ini tidak akan muncul di daftar Anda.<\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"589\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1024x589.webp\" alt=\"\" class=\"wp-image-66841\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1024x589.webp 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-300x173.webp 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-768x442.webp 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1536x884.webp 1536w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-2048x1179.webp 2048w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-360x207.webp 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"425\" height=\"207\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-button.webp\" alt=\"\" class=\"wp-image-66870\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-button.webp 425w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-button-300x146.webp 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-button-360x175.webp 360w\" sizes=\"(max-width: 425px) 100vw, 425px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Anda dapat membatalkan pesanan pembelian dengan mengedit informasi, tetapi Anda dapat melakukannya jika Anda tidak ingin pesanan ini muncul di daftar Anda: Sekarang, pesanan pembelian ini tidak akan muncul di daftar Anda.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[2265],"doc_tag":[],"class_list":["post-79656","docs","type-docs","status-publish","hentry","doc_category-pesanan-pembelian"],"acf":[],"year_month":"2026-09","word_count":68,"total_views":"178","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/id\/author\/bettina\/"},"doc_category_info":[{"term_name":"Pesanan Pembelian","term_url":"https:\/\/skyplanner.ai\/id\/docs-category\/pesanan-pembelian\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cara menghapus pesanan Pembelian &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cara menghapus pesanan Pembelian\" \/>\n<meta property=\"og:description\" content=\"Anda dapat membatalkan pesanan pembelian dengan mengedit informasi, tetapi Anda dapat melakukannya jika Anda tidak ingin pesanan ini muncul di daftar Anda: Sekarang, pesanan pembelian ini tidak akan muncul di daftar Anda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T08:16:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2078\" \/>\n\t<meta property=\"og:image:height\" content=\"1196\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/docs\\\/cara-menghapus-pesanan-pembelian\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/docs\\\/cara-menghapus-pesanan-pembelian\\\/\",\"name\":\"Cara menghapus pesanan Pembelian &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/docs\\\/cara-menghapus-pesanan-pembelian\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/docs\\\/cara-menghapus-pesanan-pembelian\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/delete-purchase-order-1024x589.webp\",\"datePublished\":\"2025-04-30T08:26:08+00:00\",\"dateModified\":\"2025-10-08T08:16:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/docs\\\/cara-menghapus-pesanan-pembelian\\\/#breadcrumb\"},\"inLanguage\":\"id\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyplanner.ai\\\/id\\\/docs\\\/cara-menghapus-pesanan-pembelian\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/docs\\\/cara-menghapus-pesanan-pembelian\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/delete-purchase-order-1024x589.webp\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/delete-purchase-order-1024x589.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/docs\\\/cara-menghapus-pesanan-pembelian\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/docs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cara menghapus pesanan Pembelian\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/#website\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/id\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@SkyPlannerAPS\",\"https:\\\/\\\/www.capterra.com\\\/p\\\/265911\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.trustradius.com\\\/products\\\/skyplanner-aps\\\/reviews\",\"https:\\\/\\\/www.saasworthy.com\\\/product\\\/skyplanner-aps\",\"https:\\\/\\\/sourceforge.net\\\/software\\\/product\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.g2.com\\\/products\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.getapp.com\\\/project-management-planning-software\\\/a\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.softwareadvice.com\\\/cmms\\\/skyplanner-aps-profile\\\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/trial\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cara menghapus pesanan Pembelian &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/","og_locale":"id_ID","og_type":"article","og_title":"Cara menghapus pesanan Pembelian","og_description":"Anda dapat membatalkan pesanan pembelian dengan mengedit informasi, tetapi Anda dapat melakukannya jika Anda tidak ingin pesanan ini muncul di daftar Anda: Sekarang, pesanan pembelian ini tidak akan muncul di daftar Anda.","og_url":"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-08T08:16:24+00:00","og_image":[{"width":2078,"height":1196,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/","url":"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/","name":"Cara menghapus pesanan Pembelian &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/id\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1024x589.webp","datePublished":"2025-04-30T08:26:08+00:00","dateModified":"2025-10-08T08:16:24+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/#breadcrumb"},"inLanguage":"id","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/"]}]},{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1024x589.webp","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/04\/delete-purchase-order-1024x589.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/id\/docs\/cara-menghapus-pesanan-pembelian\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/id\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/id\/docs\/"},{"@type":"ListItem","position":3,"name":"Cara menghapus pesanan Pembelian"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/id\/#website","url":"https:\/\/skyplanner.ai\/id\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/id\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/id\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/skyplanner.ai\/id\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/id\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/id\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Anda dapat membatalkan pesanan pembelian dengan mengedit informasi, tetapi Anda dapat melakukannya jika Anda tidak ingin pesanan ini muncul di daftar Anda: Sekarang, pesanan pembelian ini tidak akan muncul di daftar Anda.","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/id\/wp-json\/wp\/v2\/docs\/79656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/id\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/id\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/id\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/id\/wp-json\/wp\/v2\/comments?post=79656"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/id\/wp-json\/wp\/v2\/docs\/79656\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/id\/wp-json\/wp\/v2\/media?parent=79656"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/id\/wp-json\/wp\/v2\/doc_category?post=79656"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/id\/wp-json\/wp\/v2\/doc_tag?post=79656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}