{"id":61404,"date":"2025-03-06T08:03:56","date_gmt":"2025-03-06T08:03:56","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/produits-et-materiaux\/"},"modified":"2025-10-07T11:10:52","modified_gmt":"2025-10-07T11:10:52","password":"","slug":"produits-et-materiaux","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/","title":{"rendered":"Produits et mat\u00e9riaux"},"content":{"rendered":"\n<p>Nous allons voir ici comment vous pouvez cr\u00e9er des produits et des mat\u00e9riaux et comment vous pouvez les attacher \u00e0 vos commandes avec l&rsquo;API Skyplanner. Nous vous montrerons \u00e9galement comment cr\u00e9er des \u00e9tapes de processus par d\u00e9faut pour vos produits et comment cr\u00e9er des \u00e9l\u00e9ments de commande en utilisant ces valeurs par d\u00e9faut. <\/p>\n\n<h4 class=\"wp-block-heading\">Cr\u00e9ation d&rsquo;un produit\/mat\u00e9riau<\/h4>\n\n<p>La cr\u00e9ation et la mise \u00e0 jour des produits et des mat\u00e9riaux s&rsquo;effectuent via le m\u00eame point API : <mark style=\"background-color:var(--contrast-3)\" class=\"has-inline-color\">\/products<\/mark>. Le type de produit est d\u00e9fini par l&rsquo;<strong>attribut type<\/strong>: &lsquo;product&rsquo; ou &lsquo;material&rsquo; <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"616\" height=\"272\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14.png\" alt=\"\" class=\"wp-image-54635\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14.png 616w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14-300x132.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14-360x159.png 360w\" sizes=\"(max-width: 616px) 100vw, 616px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 1.<\/strong>  Cr\u00e9er un produit<\/figcaption><\/figure>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"613\" height=\"284\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-11.png\" alt=\"\" class=\"wp-image-54548\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-11.png 613w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-11-300x139.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-11-360x167.png 360w\" sizes=\"(max-width: 613px) 100vw, 613px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 2.<\/strong>  Cr\u00e9ation d&rsquo;un mat\u00e9riau<\/figcaption><\/figure>\n\n<p>Lorsque vous cr\u00e9ez des produits et des mat\u00e9riaux, veillez \u00e0 d\u00e9finir la valeur <strong>is_active<\/strong> comme \u00e9tant vraie si vous souhaitez que le produit\/mat\u00e9riau soit affich\u00e9 comme \u00e9tant actif dans la liste des produits. Notez \u00e9galement que vous pouvez d\u00e9finir la quantit\u00e9 de stock disponible \u00e0 l&rsquo;aide de l&rsquo;attribut <strong>free_amount<\/strong>. <\/p>\n\n<h4 class=\"wp-block-heading\">Cr\u00e9ation d&rsquo;\u00e9tapes de processus par d\u00e9faut pour un produit<\/h4>\n\n<p>Avant d&rsquo;ajouter des \u00e9tapes de processus par d\u00e9faut pour un produit, vous devez disposer des stations de travail appropri\u00e9es. Les stations de travail peuvent \u00eatre cr\u00e9\u00e9es soit via l&rsquo;interface utilisateur de Skyplanner, soit via le <mark style=\"background-color:var(--contrast-3)\" class=\"has-inline-color\"> point de terminaison \/workstages<\/mark>. <\/p>\n\n<p>L&rsquo;ajout d&rsquo;\u00e9tapes de processus par d\u00e9faut s&rsquo;effectue \u00e0 partir du point de terminaison <mark style=\"background-color:var(--contrast-3)\" class=\"has-inline-color\">\/products\/jobs\/{productId}<\/mark>.<\/p>\n\n<p>Par exemple, si vous souhaitez ajouter une \u00e9tape par d\u00e9faut au produit avec l&rsquo;identifiant 22220, vous devez effectuer une demande POST comme suit :<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"618\" height=\"401\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-16.png\" alt=\"\" class=\"wp-image-54694\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-16.png 618w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-16-300x195.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-16-360x234.png 360w\" sizes=\"(max-width: 618px) 100vw, 618px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 3.<\/strong>  Ajout d&rsquo;une \u00e9tape du processus par d\u00e9faut<\/figcaption><\/figure>\n\n<p>Quelques domaines notables :<\/p>\n\n<ul class=\"wp-block-list\">\n<li>num\u00e9ro de commande\n<ul class=\"wp-block-list\">\n<li>Il s&rsquo;agit d&rsquo;un num\u00e9ro d&rsquo;index qui indique \u00e0 Skyplanner l&rsquo;ordre dans lequel les \u00e9tapes du processus doivent \u00eatre accomplies.<\/li>\n\n\n\n<li>Par exemple : la premi\u00e8re \u00e9tape obtient la valeur 1, la deuxi\u00e8me \u00e9tape obtient la valeur 3, la troisi\u00e8me \u00e9tape obtient la valeur 3 et ainsi de suite&#8230;<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>postes de travail\n<ul class=\"wp-block-list\">\n<li>Il s&rsquo;agit d&rsquo;une liste de postes de travail sur lesquels cette \u00e9tape du processus peut \u00eatre planifi\u00e9e.<\/li>\n\n\n\n<li>Donnez ici les identifiants des stations de travail sous forme de liste s\u00e9par\u00e9e par des virgules, comme ceci : \u00ab\u00a061,62,63\u00a0\u00bb<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>variation_du_temps\n<ul class=\"wp-block-list\">\n<li>Valeurs possibles : time_per_pcs, pcs_per_time, fixed_time<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>dur\u00e9e, temps de r\u00e9glage, temps de r\u00e9glage\n<ul class=\"wp-block-list\">\n<li>Donnez ces valeurs en <em>secondes<\/em><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n<h4 class=\"wp-block-heading\">Mise \u00e0 jour d&rsquo;une \u00e9tape du processus par d\u00e9faut<\/h4>\n\n<p>Lors de la mise \u00e0 jour d&rsquo;une \u00e9tape du processus par d\u00e9faut, vous devez utiliser l&rsquo;attribut <strong>order_number<\/strong> pour sp\u00e9cifier l&rsquo;\u00e9tape \u00e0 mettre \u00e0 jour.<\/p>\n\n<p>Par exemple, la premi\u00e8re \u00e9tape du processus<strong>(num\u00e9ro de commande 1)<\/strong> dans ce produit est r\u00e9alis\u00e9e \u00e0 l&rsquo;aide d&rsquo;une demande PUT comme celle-ci :<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"622\" height=\"389\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-19.png\" alt=\"\" class=\"wp-image-54813\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-19.png 622w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-19-300x188.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-19-360x225.png 360w\" sizes=\"(max-width: 622px) 100vw, 622px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 4.<\/strong>  Mise \u00e0 jour d&rsquo;une \u00e9tape du processus par d\u00e9faut<\/figcaption><\/figure>\n\n<h4 class=\"wp-block-heading\">Suppression des \u00e9tapes du processus par d\u00e9faut<\/h4>\n\n<p>La suppression des \u00e9tapes du processus par d\u00e9faut s&rsquo;effectue \u00e9galement \u00e0 l&rsquo;aide des valeurs <strong>order_number<\/strong>.<\/p>\n\n<p>Les num\u00e9ros de commande sont donn\u00e9s dans un tableau comme celui-ci :<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"647\" height=\"263\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-21.png\" alt=\"\" class=\"wp-image-54871\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-21.png 647w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-21-300x122.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-21-360x146.png 360w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 5.<\/strong>  Suppression des \u00e9tapes du processus par d\u00e9faut<\/figcaption><\/figure>\n\n<h5 class=\"wp-block-heading\">Ajout d&rsquo;un mat\u00e9riau\/sous-produit \u00e0 un produit<\/h5>\n\n<p>Pour attacher un mat\u00e9riau ou un sous-produit, nous devons utiliser le point de terminaison <mark style=\"background-color:var(--contrast-3)\" class=\"has-inline-color\">\/sub-produits<\/mark>.<\/p>\n\n<p>Le processus est assez simple : nous pla\u00e7ons l&rsquo;identifiant du mat\u00e9riau ou du sous-produit dans l&rsquo;attribut <strong>production_planning_product_id<\/strong> et l&rsquo;identifiant du produit auquel nous voulons que le mat\u00e9riau\/sous-produit soit attach\u00e9 dans l&rsquo;attribut <strong>production_planning_product_parent_id<\/strong>.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"627\" height=\"256\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-22.png\" alt=\"\" class=\"wp-image-54999\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-22.png 627w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-22-300x122.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-22-360x147.png 360w\" sizes=\"(max-width: 627px) 100vw, 627px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 6.<\/strong>  Attacher un mat\u00e9riau \u00e0 un produit<\/figcaption><\/figure>\n\n<h5 class=\"wp-block-heading\">Ajout d&rsquo;un mat\u00e9riau \u00e0 un article de commande<\/h5>\n\n<p>Vous pouvez \u00e9galement attacher des mat\u00e9riaux directement \u00e0 un \u00e9l\u00e9ment de commande en utilisant le point de <mark style=\"background-color:var(--contrast-3)\" class=\"has-inline-color\"> terminaison \/row-materials<\/mark>. De cette fa\u00e7on, vous pouvez attacher des mat\u00e9riaux suppl\u00e9mentaires ou utiliser une liste de mat\u00e9riaux compl\u00e8tement diff\u00e9rente dans un \u00e9l\u00e9ment de commande par rapport aux mat\u00e9riaux par d\u00e9faut d\u00e9finis pour les produits. Notez que vous ne pouvez avoir qu&rsquo;une seule entit\u00e9 row-material pour un \u00e9l\u00e9ment de commande et pour chaque mat\u00e9riau. Vous ne pouvez donc pas cr\u00e9er deux entit\u00e9s ayant le m\u00eame <strong>num\u00e9ro d&rsquo;identification de produit de planification de la production <\/strong>pour le m\u00eame <strong>num\u00e9ro d&rsquo;identification de ligne de commande de phaser<\/strong>.   <\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"643\" height=\"254\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-24.png\" alt=\"\" class=\"wp-image-55057\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-24.png 643w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-24-300x119.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-24-360x142.png 360w\" sizes=\"(max-width: 643px) 100vw, 643px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 7.<\/strong>  Ajout d&rsquo;un article \u00e0 un poste de commande<\/figcaption><\/figure>\n\n<h4 class=\"wp-block-heading\">Mise \u00e0 jour du niveau de stock<\/h4>\n\n<p>Vous pouvez mettre \u00e0 jour le niveau de stock du produit ou de l&rsquo;article en envoyant une demande PUT avec l&rsquo;attribut <strong>free_amount<\/strong>.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"637\" height=\"219\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-40.png\" alt=\"\" class=\"wp-image-56668\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-40.png 637w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-40-300x103.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-40-360x124.png 360w\" sizes=\"(max-width: 637px) 100vw, 637px\" \/><figcaption class=\"wp-element-caption\"><strong>Fig. 8.<\/strong>  Mise \u00e0 jour du niveau de stock<\/figcaption><\/figure>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous allons voir ici comment vous pouvez cr\u00e9er des produits et des mat\u00e9riaux et comment vous pouvez les attacher \u00e0 vos commandes avec l&rsquo;API Skyplanner. Nous vous montrerons \u00e9galement comment cr\u00e9er des \u00e9tapes de processus par d\u00e9faut pour vos produits et comment cr\u00e9er des \u00e9l\u00e9ments de commande en utilisant ces valeurs par d\u00e9faut. Cr\u00e9ation d&rsquo;un &#8230; <a title=\"Produits et mat\u00e9riaux\" class=\"read-more\" href=\"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/\" aria-label=\"Read more about Produits et mat\u00e9riaux\">Lire plus<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[623],"doc_tag":[624,1520],"class_list":["post-61404","docs","type-docs","status-publish","hentry","doc_category-integrations-fr","doc_tag-api-fr","doc_tag-integration-fr"],"acf":[],"year_month":"2026-07","word_count":748,"total_views":"184","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"Sami","author_nicename":"sami","author_url":"https:\/\/skyplanner.ai\/fr\/author\/sami\/"},"doc_category_info":[{"term_name":"Int\u00e9grations","term_url":"https:\/\/skyplanner.ai\/fr\/docs-category\/integrations-fr\/"}],"doc_tag_info":[{"term_name":"API","term_url":"https:\/\/skyplanner.ai\/fr\/docs-tag\/api-fr\/"},{"term_name":"Int\u00e9gration","term_url":"https:\/\/skyplanner.ai\/fr\/docs-tag\/integration-fr\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Produits et mat\u00e9riaux &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Produits et mat\u00e9riaux\" \/>\n<meta property=\"og:description\" content=\"Nous allons voir ici comment vous pouvez cr\u00e9er des produits et des mat\u00e9riaux et comment vous pouvez les attacher \u00e0 vos commandes avec l&rsquo;API Skyplanner. Nous vous montrerons \u00e9galement comment cr\u00e9er des \u00e9tapes de processus par d\u00e9faut pour vos produits et comment cr\u00e9er des \u00e9l\u00e9ments de commande en utilisant ces valeurs par d\u00e9faut. Cr\u00e9ation d&rsquo;un ... Lire plus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T11:10:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"616\" \/>\n\t<meta property=\"og:image:height\" content=\"272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/\",\"url\":\"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/\",\"name\":\"Produits et mat\u00e9riaux &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14.png\",\"datePublished\":\"2025-03-06T08:03:56+00:00\",\"dateModified\":\"2025-10-07T11:10:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/#primaryimage\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14.png\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/fr\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Produits et mat\u00e9riaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/fr\/#website\",\"url\":\"https:\/\/skyplanner.ai\/fr\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/fr\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/skyplanner.ai\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Produits et mat\u00e9riaux &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Produits et mat\u00e9riaux","og_description":"Nous allons voir ici comment vous pouvez cr\u00e9er des produits et des mat\u00e9riaux et comment vous pouvez les attacher \u00e0 vos commandes avec l&rsquo;API Skyplanner. Nous vous montrerons \u00e9galement comment cr\u00e9er des \u00e9tapes de processus par d\u00e9faut pour vos produits et comment cr\u00e9er des \u00e9l\u00e9ments de commande en utilisant ces valeurs par d\u00e9faut. Cr\u00e9ation d&rsquo;un ... Lire plus","og_url":"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T11:10:52+00:00","og_image":[{"width":616,"height":272,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/","url":"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/","name":"Produits et mat\u00e9riaux &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14.png","datePublished":"2025-03-06T08:03:56+00:00","dateModified":"2025-10-07T11:10:52+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/03\/image-14.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/fr\/docs\/produits-et-materiaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/fr\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/fr\/docs\/"},{"@type":"ListItem","position":3,"name":"Produits et mat\u00e9riaux"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/fr\/#website","url":"https:\/\/skyplanner.ai\/fr\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/fr\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/skyplanner.ai\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"Sami","author_link":"https:\/\/skyplanner.ai\/fr\/author\/sami\/"},"uagb_comment_info":0,"uagb_excerpt":"Nous allons voir ici comment vous pouvez cr\u00e9er des produits et des mat\u00e9riaux et comment vous pouvez les attacher \u00e0 vos commandes avec l&rsquo;API Skyplanner. Nous vous montrerons \u00e9galement comment cr\u00e9er des \u00e9tapes de processus par d\u00e9faut pour vos produits et comment cr\u00e9er des \u00e9l\u00e9ments de commande en utilisant ces valeurs par d\u00e9faut. Cr\u00e9ation d&rsquo;un\u2026","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/docs\/61404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/comments?post=61404"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/docs\/61404\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/media?parent=61404"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/doc_category?post=61404"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/doc_tag?post=61404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}