{"id":59596,"date":"2025-02-18T11:51:24","date_gmt":"2025-02-18T11:51:24","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/"},"modified":"2025-10-07T09:27:02","modified_gmt":"2025-10-07T09:27:02","password":"","slug":"comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/","title":{"rendered":"Comment afficher tous les postes de travail dans la chronologie de GANTT ?"},"content":{"rendered":"\n<p>Pour voir tous les postes de travail dans la chronologie de GANTT :<\/p>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"178\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92-1024x178.png\" alt=\"\" class=\"wp-image-51623\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92-1024x178.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92-300x52.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92-768x134.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92-1536x268.png 1536w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92-360x63.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92.png 1820w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Cliquez sur le bouton Toutes les stations de travail sur le c\u00f4t\u00e9 gauche de la ligne de temps de GANTT.<\/li>\n<\/ul>\n\n<p class=\"has-text-align-center\"><img decoding=\"async\" src=\"https:\/\/cdn-assets.productfruits.com\/fa252e6c-d6eb-47d1-addb-16a634788466\"\/><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Un menu appara\u00eet ; cliquez sur la bo\u00eete Tous les postes de travail.  <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"845\" height=\"376\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-93.png\" alt=\"\" class=\"wp-image-51652\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-93.png 845w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-93-300x133.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-93-768x342.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-93-360x160.png 360w\" sizes=\"(max-width: 845px) 100vw, 845px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Enfin, cliquez n&rsquo;importe o\u00f9 ailleurs sur la ligne de temps de GANTT pour fermer le menu et voir tous les postes de travail.<\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"270\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-94-1024x270.png\" alt=\"\" class=\"wp-image-51681\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-94-1024x270.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-94-300x79.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-94-768x203.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-94-1536x406.png 1536w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-94-360x95.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-94.png 1818w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Pour voir tous les postes de travail dans la chronologie de GANTT :<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[2033],"doc_tag":[576,840],"class_list":["post-59596","docs","type-docs","status-publish","hentry","doc_category-postes-de-travail-et-groupes-de-postes-de-travail","doc_tag-diagramme-de-gantt","doc_tag-postes-de-travail"],"acf":[],"year_month":"2026-09","word_count":70,"total_views":"208","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/fr\/author\/bettina\/"},"doc_category_info":[{"term_name":"Postes de travail et groupes de postes de travail","term_url":"https:\/\/skyplanner.ai\/fr\/docs-category\/postes-de-travail-et-groupes-de-postes-de-travail\/"}],"doc_tag_info":[{"term_name":"Diagramme de Gantt","term_url":"https:\/\/skyplanner.ai\/fr\/docs-tag\/diagramme-de-gantt\/"},{"term_name":"Postes de travail","term_url":"https:\/\/skyplanner.ai\/fr\/docs-tag\/postes-de-travail\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comment afficher tous les postes de travail dans la chronologie de GANTT ? &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment afficher tous les postes de travail dans la chronologie de GANTT ?\" \/>\n<meta property=\"og:description\" content=\"Pour voir tous les postes de travail dans la chronologie de GANTT :\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T09:27:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1820\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/docs\\\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/docs\\\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\\\/\",\"name\":\"Comment afficher tous les postes de travail dans la chronologie de GANTT ? &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/docs\\\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/docs\\\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-92-1024x178.png\",\"datePublished\":\"2025-02-18T11:51:24+00:00\",\"dateModified\":\"2025-10-07T09:27:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/docs\\\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/docs\\\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/docs\\\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-92-1024x178.png\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-92-1024x178.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/docs\\\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/docs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comment afficher tous les postes de travail dans la chronologie de GANTT ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@SkyPlannerAPS\",\"https:\\\/\\\/www.capterra.com\\\/p\\\/265911\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.trustradius.com\\\/products\\\/skyplanner-aps\\\/reviews\",\"https:\\\/\\\/www.saasworthy.com\\\/product\\\/skyplanner-aps\",\"https:\\\/\\\/sourceforge.net\\\/software\\\/product\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.g2.com\\\/products\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.getapp.com\\\/project-management-planning-software\\\/a\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.softwareadvice.com\\\/cmms\\\/skyplanner-aps-profile\\\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/trial\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comment afficher tous les postes de travail dans la chronologie de GANTT ? &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment afficher tous les postes de travail dans la chronologie de GANTT ?","og_description":"Pour voir tous les postes de travail dans la chronologie de GANTT :","og_url":"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T09:27:02+00:00","og_image":[{"width":1820,"height":317,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/","url":"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/","name":"Comment afficher tous les postes de travail dans la chronologie de GANTT ? &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92-1024x178.png","datePublished":"2025-02-18T11:51:24+00:00","dateModified":"2025-10-07T09:27:02+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92-1024x178.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-92-1024x178.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/fr\/docs\/comment-afficher-tous-les-postes-de-travail-dans-la-chronologie-de-gantt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/fr\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/fr\/docs\/"},{"@type":"ListItem","position":3,"name":"Comment afficher tous les postes de travail dans la chronologie de GANTT ?"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/fr\/#website","url":"https:\/\/skyplanner.ai\/fr\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/fr\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/skyplanner.ai\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/fr\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Pour voir tous les postes de travail dans la chronologie de GANTT :","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/docs\/59596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/comments?post=59596"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/docs\/59596\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/media?parent=59596"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/doc_category?post=59596"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/fr\/wp-json\/wp\/v2\/doc_tag?post=59596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}