{"id":61141,"date":"2025-02-17T09:53:47","date_gmt":"2025-02-17T09:53:47","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/hakutoiminto-gantt-aikajanalla\/"},"modified":"2025-10-07T09:11:30","modified_gmt":"2025-10-07T09:11:30","password":"","slug":"hakutoiminto-gantt-aikajanalla","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/","title":{"rendered":"Hakutoiminto GANTT-aikajanalla"},"content":{"rendered":"\n<p>Lis\u00e4ksi on my\u00f6s hakutoiminto. Voit etsi\u00e4 suunniteltuja t\u00f6it\u00e4 ty\u00f6numeron perusteella ja tarkastella niit\u00e4 helposti aikajanalla. <\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"503\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-1024x503.png\" alt=\"\" class=\"wp-image-61106\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-1024x503.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-300x147.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-768x377.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-1536x754.png 1536w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-360x177.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline.png 1793w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lis\u00e4ksi on my\u00f6s hakutoiminto. Voit etsi\u00e4 suunniteltuja t\u00f6it\u00e4 ty\u00f6numeron perusteella ja tarkastella niit\u00e4 helposti aikajanalla.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[1936],"doc_tag":[578],"class_list":["post-61141","docs","type-docs","status-publish","hentry","doc_category-peruskaytto","doc_tag-gantt-kaavio"],"acf":[],"year_month":"2026-05","word_count":19,"total_views":"129","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/fi\/author\/bettina\/"},"doc_category_info":[{"term_name":"Perusk\u00e4ytt\u00f6","term_url":"https:\/\/skyplanner.ai\/fi\/docs-category\/peruskaytto\/"}],"doc_tag_info":[{"term_name":"Gantt-kaavio","term_url":"https:\/\/skyplanner.ai\/fi\/docs-tag\/gantt-kaavio\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hakutoiminto GANTT-aikajanalla &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hakutoiminto GANTT-aikajanalla\" \/>\n<meta property=\"og:description\" content=\"Lis\u00e4ksi on my\u00f6s hakutoiminto. Voit etsi\u00e4 suunniteltuja t\u00f6it\u00e4 ty\u00f6numeron perusteella ja tarkastella niit\u00e4 helposti aikajanalla.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T09:11:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1793\" \/>\n\t<meta property=\"og:image:height\" content=\"880\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/\",\"url\":\"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/\",\"name\":\"Hakutoiminto GANTT-aikajanalla &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/fi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-1024x503.png\",\"datePublished\":\"2025-02-17T09:53:47+00:00\",\"dateModified\":\"2025-10-07T09:11:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/#primaryimage\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-1024x503.png\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-1024x503.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/fi\/etusivu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/fi\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hakutoiminto GANTT-aikajanalla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/fi\/#website\",\"url\":\"https:\/\/skyplanner.ai\/fi\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/fi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/fi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/fi\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/fi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\/\/skyplanner.ai\/fi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/fi\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hakutoiminto GANTT-aikajanalla &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/","og_locale":"fi_FI","og_type":"article","og_title":"Hakutoiminto GANTT-aikajanalla","og_description":"Lis\u00e4ksi on my\u00f6s hakutoiminto. Voit etsi\u00e4 suunniteltuja t\u00f6it\u00e4 ty\u00f6numeron perusteella ja tarkastella niit\u00e4 helposti aikajanalla.","og_url":"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T09:11:30+00:00","og_image":[{"width":1793,"height":880,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/","url":"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/","name":"Hakutoiminto GANTT-aikajanalla &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/fi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-1024x503.png","datePublished":"2025-02-17T09:53:47+00:00","dateModified":"2025-10-07T09:11:30+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/"]}]},{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-1024x503.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/Search-function-in-gantt-timeline-1024x503.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/fi\/docs\/hakutoiminto-gantt-aikajanalla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/fi\/etusivu\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/fi\/docs\/"},{"@type":"ListItem","position":3,"name":"Hakutoiminto GANTT-aikajanalla"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/fi\/#website","url":"https:\/\/skyplanner.ai\/fi\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/fi\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/fi\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/skyplanner.ai\/fi\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/fi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/fi\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Lis\u00e4ksi on my\u00f6s hakutoiminto. Voit etsi\u00e4 suunniteltuja t\u00f6it\u00e4 ty\u00f6numeron perusteella ja tarkastella niit\u00e4 helposti aikajanalla.","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/fi\/wp-json\/wp\/v2\/docs\/61141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/fi\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/fi\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/fi\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/fi\/wp-json\/wp\/v2\/comments?post=61141"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/fi\/wp-json\/wp\/v2\/docs\/61141\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/fi\/wp-json\/wp\/v2\/media?parent=61141"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/fi\/wp-json\/wp\/v2\/doc_category?post=61141"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/fi\/wp-json\/wp\/v2\/doc_tag?post=61141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}