{"id":58014,"date":"2025-02-20T08:04:56","date_gmt":"2025-02-20T08:04:56","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/como-editar-una-etapa-del-proceso\/"},"modified":"2025-10-07T10:54:40","modified_gmt":"2025-10-07T10:54:40","password":"","slug":"como-editar-una-etapa-del-proceso","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/","title":{"rendered":"C\u00f3mo editar una Etapa del Proceso"},"content":{"rendered":"\n<p>Si quieres editar una etapa de proceso existente:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Ve a<strong> Pedidos<\/strong> y selecciona <strong>Procesar pasos<\/strong>.<\/li>\n\n\n\n<li>A continuaci\u00f3n, ver\u00e1s <strong>el panel Pasos del proceso<\/strong>. Aqu\u00ed encontrar\u00e1s todos los pasos del proceso que tu empresa puede elaborar.   <\/li>\n\n\n\n<li>Haz clic en el <strong>Bot\u00f3n Editar<\/strong> situado en la parte inferior derecha del paso del proceso que quieras editar.<\/li>\n\n\n\n<li>Aparecer\u00e1 una ventana con la informaci\u00f3n del paso actual del proceso. Cambia la informaci\u00f3n que quieras actualizar. <\/li>\n\n\n\n<li>Por \u00faltimo, haz clic en <strong>Guardar<\/strong>.  <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"434\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132-1024x434.png\" alt=\"\" class=\"wp-image-52821\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132-1024x434.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132-300x127.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132-768x325.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132-1536x651.png 1536w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132-360x153.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132.png 1860w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Si quieres editar una etapa de proceso existente:<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[2234],"doc_tag":[],"class_list":["post-58014","docs","type-docs","status-publish","hentry","doc_category-pasos-del-proceso"],"acf":[],"year_month":"2026-09","word_count":83,"total_views":"173","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/es\/author\/bettina\/"},"doc_category_info":[{"term_name":"Pasos del proceso","term_url":"https:\/\/skyplanner.ai\/es\/docs-category\/pasos-del-proceso\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>C\u00f3mo editar una Etapa del Proceso &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo editar una Etapa del Proceso\" \/>\n<meta property=\"og:description\" content=\"Si quieres editar una etapa de proceso existente:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T10:54:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1860\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/docs\\\/como-editar-una-etapa-del-proceso\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/docs\\\/como-editar-una-etapa-del-proceso\\\/\",\"name\":\"C\u00f3mo editar una Etapa del Proceso &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/docs\\\/como-editar-una-etapa-del-proceso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/docs\\\/como-editar-una-etapa-del-proceso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-132-1024x434.png\",\"datePublished\":\"2025-02-20T08:04:56+00:00\",\"dateModified\":\"2025-10-07T10:54:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/docs\\\/como-editar-una-etapa-del-proceso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyplanner.ai\\\/es\\\/docs\\\/como-editar-una-etapa-del-proceso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/docs\\\/como-editar-una-etapa-del-proceso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-132-1024x434.png\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/image-132-1024x434.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/docs\\\/como-editar-una-etapa-del-proceso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/docs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo editar una Etapa del Proceso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\\\/\\\/skyplanner.ai\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\\\/\\\/skyplanner.ai\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@SkyPlannerAPS\",\"https:\\\/\\\/www.capterra.com\\\/p\\\/265911\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.trustradius.com\\\/products\\\/skyplanner-aps\\\/reviews\",\"https:\\\/\\\/www.saasworthy.com\\\/product\\\/skyplanner-aps\",\"https:\\\/\\\/sourceforge.net\\\/software\\\/product\\\/SkyPlanner-APS\\\/\",\"https:\\\/\\\/www.g2.com\\\/products\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.getapp.com\\\/project-management-planning-software\\\/a\\\/skyplanner-aps\\\/\",\"https:\\\/\\\/www.softwareadvice.com\\\/cmms\\\/skyplanner-aps-profile\\\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\\\/\\\/skyplanner.ai\\\/trial\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"C\u00f3mo editar una Etapa del Proceso &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo editar una Etapa del Proceso","og_description":"Si quieres editar una etapa de proceso existente:","og_url":"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T10:54:40+00:00","og_image":[{"width":1860,"height":788,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/","url":"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/","name":"C\u00f3mo editar una Etapa del Proceso &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132-1024x434.png","datePublished":"2025-02-20T08:04:56+00:00","dateModified":"2025-10-07T10:54:40+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132-1024x434.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-132-1024x434.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/es\/docs\/como-editar-una-etapa-del-proceso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/es\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/es\/docs\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo editar una Etapa del Proceso"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/es\/#website","url":"https:\/\/skyplanner.ai\/es\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/es\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/skyplanner.ai\/es\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/es\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Si quieres editar una etapa de proceso existente:","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/docs\/58014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/comments?post=58014"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/docs\/58014\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/media?parent=58014"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/doc_category?post=58014"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/doc_tag?post=58014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}