{"id":49076,"date":"2025-02-12T14:28:03","date_gmt":"2025-02-12T14:28:03","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/"},"modified":"2025-10-07T08:22:57","modified_gmt":"2025-10-07T08:22:57","password":"","slug":"como-anadir-un-nuevo-puesto-de-trabajo","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/","title":{"rendered":"C\u00f3mo a\u00f1adir una nueva estaci\u00f3n de trabajo"},"content":{"rendered":"\n<p>Si quieres a\u00f1adir un nuevo puesto de trabajo:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Iremos a <strong>Recursos<\/strong> y seleccionaremos <strong>Estaciones de Trabajo<\/strong>. El programa te llevar\u00e1 a una p\u00e1gina que contiene todas tus estaciones de trabajo existentes.   <br\/><\/li>\n\n\n\n<li>En la parte superior derecha, haremos clic en<strong>\u00ab+<\/strong> <strong>Crear estaci\u00f3n de trabajo<\/strong>\u00ab. Observa que este mismo bot\u00f3n te dir\u00e1 cu\u00e1ntas estaciones de trabajo tienes disponibles en tu <strong>plan SkyPlanner<\/strong>.   <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"219\" height=\"49\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-53.png\" alt=\"\" class=\"wp-image-47206\"\/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>A continuaci\u00f3n, a\u00f1adir\u00e1s un nombre a esta estaci\u00f3n de trabajo, elegir\u00e1s un responsable y escoger\u00e1s otras opciones que describan esta estaci\u00f3n de trabajo en particular.  <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"224\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-54-1024x224.png\" alt=\"\" class=\"wp-image-47235\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-54-1024x224.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-54-300x66.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-54-768x168.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-54-360x79.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-54.png 1504w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Por \u00faltimo, haz clic en <strong>Guardar<\/strong>.  <\/li>\n\n\n\n<li>Ahora haz clic en <strong>la flecha hacia atr\u00e1s<\/strong> para ver tu nueva estaci\u00f3n de trabajo en la lista anterior.<\/li>\n<\/ul>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si quieres a\u00f1adir un nuevo puesto de trabajo:<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[1867],"doc_tag":[],"class_list":["post-49076","docs","type-docs","status-publish","hentry","doc_category-estaciones-de-trabajo"],"acf":[],"year_month":"2026-07","word_count":124,"total_views":"150","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/es\/author\/bettina\/"},"doc_category_info":[{"term_name":"Estaciones de trabajo","term_url":"https:\/\/skyplanner.ai\/es\/docs-category\/estaciones-de-trabajo\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>C\u00f3mo a\u00f1adir una nueva estaci\u00f3n de trabajo &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo a\u00f1adir una nueva estaci\u00f3n de trabajo\" \/>\n<meta property=\"og:description\" content=\"Si quieres a\u00f1adir un nuevo puesto de trabajo:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T08:22:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-53.png\" \/>\n\t<meta property=\"og:image:width\" content=\"219\" \/>\n\t<meta property=\"og:image:height\" content=\"49\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/\",\"url\":\"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/\",\"name\":\"C\u00f3mo a\u00f1adir una nueva estaci\u00f3n de trabajo &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-53.png\",\"datePublished\":\"2025-02-12T14:28:03+00:00\",\"dateModified\":\"2025-10-07T08:22:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/#primaryimage\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-53.png\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-53.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/es\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f3mo a\u00f1adir una nueva estaci\u00f3n de trabajo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/es\/#website\",\"url\":\"https:\/\/skyplanner.ai\/es\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/es\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/skyplanner.ai\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"C\u00f3mo a\u00f1adir una nueva estaci\u00f3n de trabajo &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo a\u00f1adir una nueva estaci\u00f3n de trabajo","og_description":"Si quieres a\u00f1adir un nuevo puesto de trabajo:","og_url":"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T08:22:57+00:00","og_image":[{"width":219,"height":49,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-53.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/","url":"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/","name":"C\u00f3mo a\u00f1adir una nueva estaci\u00f3n de trabajo &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-53.png","datePublished":"2025-02-12T14:28:03+00:00","dateModified":"2025-10-07T08:22:57+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-53.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-53.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/es\/docs\/como-anadir-un-nuevo-puesto-de-trabajo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/es\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/es\/docs\/"},{"@type":"ListItem","position":3,"name":"C\u00f3mo a\u00f1adir una nueva estaci\u00f3n de trabajo"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/es\/#website","url":"https:\/\/skyplanner.ai\/es\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/es\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/skyplanner.ai\/es\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/es\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Si quieres a\u00f1adir un nuevo puesto de trabajo:","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/docs\/49076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/comments?post=49076"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/docs\/49076\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/media?parent=49076"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/doc_category?post=49076"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/es\/wp-json\/wp\/v2\/doc_tag?post=49076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}