{"id":59158,"date":"2025-02-20T07:55:29","date_gmt":"2025-02-20T07:55:29","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/beruecksichtigen-sie-die-materialien\/"},"modified":"2025-10-07T10:29:59","modified_gmt":"2025-10-07T10:29:59","password":"","slug":"beruecksichtigen-sie-die-materialien","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/","title":{"rendered":"Ber\u00fccksichtigen Sie die Materialien"},"content":{"rendered":"\n<p>Die \u00dcberpr\u00fcfung von Lagermaterialien vor der Produktionsplanung verhindert Verz\u00f6gerungen, indem sie sicherstellt, dass Ihre Produktion \u00fcber das verf\u00fcgt, was sie zum Starten ben\u00f6tigt. Dieser Schritt vermeidet die Verschwendung von Zeit und Ressourcen f\u00fcr angehaltene Auftr\u00e4ge. <\/p>\n\n<p><strong>Materialien ber\u00fccksichtigen<\/strong> ist eine Funktion, die <strong>Arcturus<\/strong>, die <strong>KI von SkyPlanner<\/strong>, anweist, die im Lager verf\u00fcgbaren Materialien und Ressourcen zu ber\u00fccksichtigen. Um sie zu aktivieren, m\u00fcssen Sie nur das K\u00e4stchen ankreuzen.   <\/p>\n\n<p>Um dies zu tun:  <\/p>\n\n<ul class=\"wp-block-list\">\n<li>W\u00e4hlen Sie in der <strong>GANTT Timeline<\/strong> einen beliebigen Auftrag und klicken Sie mit der rechten Maustaste darauf.  <\/li>\n\n\n\n<li>Es erscheint ein Dropdown-Men\u00fc. W\u00e4hlen Sie <strong>Auftragsregeln<\/strong>.  <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"452\" height=\"295\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111.png\" alt=\"\" class=\"wp-image-52186\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111.png 452w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111-300x196.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111-360x235.png 360w\" sizes=\"(max-width: 452px) 100vw, 452px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Es erscheint ein neues Fenster; gehen Sie zu <strong>Globale Regeln<\/strong>.  <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"1024\" height=\"618\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-112-1024x618.png\" alt=\"\" class=\"wp-image-52215\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-112-1024x618.png 1024w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-112-300x181.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-112-768x463.png 768w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-112-360x217.png 360w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-112.png 1315w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Suchen Sie die Option <strong>Materialien ber\u00fccksichtigen<\/strong> und aktivieren Sie das K\u00e4stchen.  <\/li>\n<\/ul>\n\n<p><\/p>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"608\" height=\"70\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-113.png\" alt=\"\" class=\"wp-image-52244\" srcset=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-113.png 608w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-113-300x35.png 300w, https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-113-360x41.png 360w\" sizes=\"(max-width: 608px) 100vw, 608px\" \/><\/figure>\n<\/div>\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Klicken Sie abschlie\u00dfend auf <strong>Speichern<\/strong>.  <\/li>\n<\/ul>\n\n<p>Wenn diese Funktion aktiviert ist, wird das Lager in den Produktionsplanungsprozess integriert, wobei die KI die verf\u00fcgbaren Materialien, die eingehenden Sendungen und die Lagerbest\u00e4nde analysiert, um die Produktionszeitpl\u00e4ne zu optimieren und einen reibungslosen Ablauf zu gew\u00e4hrleisten.<\/p>\n\n<p>Durch die Verwendung von <strong>Consider the materials<\/strong> kann die KI die optimale Startzeit f\u00fcr einen Auftrag genau bestimmen und so sicherstellen, dass keine Unterbrechungen aufgrund von Materialmangel auftreten.<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die \u00dcberpr\u00fcfung von Lagermaterialien vor der Produktionsplanung verhindert Verz\u00f6gerungen, indem sie sicherstellt, dass Ihre Produktion \u00fcber das verf\u00fcgt, was sie zum Starten ben\u00f6tigt. Dieser Schritt vermeidet die Verschwendung von Zeit und Ressourcen f\u00fcr angehaltene Auftr\u00e4ge. Materialien ber\u00fccksichtigen ist eine Funktion, die Arcturus, die KI von SkyPlanner, anweist, die im Lager verf\u00fcgbaren Materialien und Ressourcen zu &#8230; <a title=\"Ber\u00fccksichtigen Sie die Materialien\" class=\"read-more\" href=\"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/\" aria-label=\"Mehr Informationen \u00fcber Ber\u00fccksichtigen Sie die Materialien\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[1791],"doc_tag":[574],"class_list":["post-59158","docs","type-docs","status-publish","hentry","doc_category-globale-regeln","doc_tag-gantt-diagramm-de"],"acf":[],"year_month":"2026-05","word_count":205,"total_views":"144","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/de\/author\/bettina\/"},"doc_category_info":[{"term_name":"Globale Regeln","term_url":"https:\/\/skyplanner.ai\/de\/docs-category\/globale-regeln\/"}],"doc_tag_info":[{"term_name":"Gantt-Diagramm","term_url":"https:\/\/skyplanner.ai\/de\/docs-tag\/gantt-diagramm-de\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ber\u00fccksichtigen Sie die Materialien &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ber\u00fccksichtigen Sie die Materialien\" \/>\n<meta property=\"og:description\" content=\"Die \u00dcberpr\u00fcfung von Lagermaterialien vor der Produktionsplanung verhindert Verz\u00f6gerungen, indem sie sicherstellt, dass Ihre Produktion \u00fcber das verf\u00fcgt, was sie zum Starten ben\u00f6tigt. Dieser Schritt vermeidet die Verschwendung von Zeit und Ressourcen f\u00fcr angehaltene Auftr\u00e4ge. Materialien ber\u00fccksichtigen ist eine Funktion, die Arcturus, die KI von SkyPlanner, anweist, die im Lager verf\u00fcgbaren Materialien und Ressourcen zu ... Weiterlesen ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T10:29:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111.png\" \/>\n\t<meta property=\"og:image:width\" content=\"452\" \/>\n\t<meta property=\"og:image:height\" content=\"295\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/\",\"url\":\"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/\",\"name\":\"Ber\u00fccksichtigen Sie die Materialien &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111.png\",\"datePublished\":\"2025-02-20T07:55:29+00:00\",\"dateModified\":\"2025-10-07T10:29:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/#primaryimage\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111.png\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/de\/hauptseite\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/de\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ber\u00fccksichtigen Sie die Materialien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/de\/#website\",\"url\":\"https:\/\/skyplanner.ai\/de\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/de\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skyplanner.ai\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ber\u00fccksichtigen Sie die Materialien &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/","og_locale":"de_DE","og_type":"article","og_title":"Ber\u00fccksichtigen Sie die Materialien","og_description":"Die \u00dcberpr\u00fcfung von Lagermaterialien vor der Produktionsplanung verhindert Verz\u00f6gerungen, indem sie sicherstellt, dass Ihre Produktion \u00fcber das verf\u00fcgt, was sie zum Starten ben\u00f6tigt. Dieser Schritt vermeidet die Verschwendung von Zeit und Ressourcen f\u00fcr angehaltene Auftr\u00e4ge. Materialien ber\u00fccksichtigen ist eine Funktion, die Arcturus, die KI von SkyPlanner, anweist, die im Lager verf\u00fcgbaren Materialien und Ressourcen zu ... Weiterlesen ...","og_url":"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T10:29:59+00:00","og_image":[{"width":452,"height":295,"url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/","url":"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/","name":"Ber\u00fccksichtigen Sie die Materialien &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/#primaryimage"},"image":{"@id":"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/#primaryimage"},"thumbnailUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111.png","datePublished":"2025-02-20T07:55:29+00:00","dateModified":"2025-10-07T10:29:59+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/#primaryimage","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111.png","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/image-111.png"},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/de\/docs\/beruecksichtigen-sie-die-materialien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/de\/hauptseite\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/de\/docs\/"},{"@type":"ListItem","position":3,"name":"Ber\u00fccksichtigen Sie die Materialien"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/de\/#website","url":"https:\/\/skyplanner.ai\/de\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/de\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skyplanner.ai\/de\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/de\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Die \u00dcberpr\u00fcfung von Lagermaterialien vor der Produktionsplanung verhindert Verz\u00f6gerungen, indem sie sicherstellt, dass Ihre Produktion \u00fcber das verf\u00fcgt, was sie zum Starten ben\u00f6tigt. Dieser Schritt vermeidet die Verschwendung von Zeit und Ressourcen f\u00fcr angehaltene Auftr\u00e4ge. Materialien ber\u00fccksichtigen ist eine Funktion, die Arcturus, die KI von SkyPlanner, anweist, die im Lager verf\u00fcgbaren Materialien und Ressourcen zu&hellip;","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/docs\/59158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/comments?post=59158"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/docs\/59158\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/media?parent=59158"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/doc_category?post=59158"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/doc_tag?post=59158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}