{"id":50250,"date":"2025-02-13T10:38:17","date_gmt":"2025-02-13T10:38:17","guid":{"rendered":"https:\/\/skyplanner.ai\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/"},"modified":"2025-10-07T08:52:08","modified_gmt":"2025-10-07T08:52:08","password":"","slug":"so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu","status":"publish","type":"docs","link":"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/","title":{"rendered":"So weisen Sie allen Arbeitsstationen eine vorbeugende Wartung zu"},"content":{"rendered":"\n<p>Wenn Sie eine vorbeugende Wartung geplant haben und diese in SkyPlanner einplanen m\u00f6chten, gehen Sie folgenderma\u00dfen vor:<\/p>\n\n<p><\/p>\n\n<figure class=\"wp-block-video\"><video height=\"930\" style=\"aspect-ratio: 1906 \/ 930;\" width=\"1906\" controls=\"\" src=\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2025\/02\/How-to-add-preventive-maintenance.mp4\"><\/video><\/figure>\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Gehen Sie zu <strong>Ressourcen<\/strong> und w\u00e4hlen Sie <strong>Workstations<\/strong>.<\/li>\n\n\n\n<li>Ein neues Fenster wird ge\u00f6ffnet.<strong> <\/strong>W\u00e4hlen Sie eine Workstation aus. Klicken Sie auf das <strong>blaue Bleistiftsymbol<\/strong> auf der rechten Seite. <\/li>\n\n\n\n<li>Jetzt befinden Sie sich im Verwaltungsbereich f\u00fcr diese Workstation. Scrollen Sie nach unten und klicken Sie auf<strong>&#8222;Workstation-Ausnahme hinzuf\u00fcgen<\/strong>&#8222;. <\/li>\n\n\n\n<li>Neue Optionen werden angezeigt. F\u00fcgen Sie eine <strong>kurze Beschreibung<\/strong> hinzu, die den Grund f\u00fcr die Wartung erkl\u00e4rt. <\/li>\n\n\n\n<li>W\u00e4hlen Sie eine <strong>Zeitspanne<\/strong> aus, in der die Workstation nicht verf\u00fcgbar sein wird.<\/li>\n\n\n\n<li>Markieren Sie au\u00dferdem das K\u00e4stchen<strong>&#8222;F\u00fcr alle einstellen<\/strong>&#8222;.<\/li>\n\n\n\n<li>Klicken Sie auf <strong>Speichern<\/strong>, um den Wartungszeitraum zu best\u00e4tigen.<\/li>\n<\/ul>\n\n<p>Gehen Sie zur <strong>GANTT Timeline<\/strong>, wo die Kapazit\u00e4ten der Arbeitsstationen f\u00fcr diesen Tag nun in <strong>lachsfarbener Farbe<\/strong> angezeigt werden, was bedeutet, dass eine Wartung stattfindet.<\/p>\n\n<p>Erledigt! Die Workstation ist jetzt f\u00fcr die Wartung vorgesehen. <\/p>\n\n<p><strong>Wichtig:<\/strong> Klicken Sie auf die <strong>Schaltfl\u00e4che K\u00f6nig<\/strong>, um Ihren Terminplan zu aktualisieren.<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn Sie eine vorbeugende Wartung geplant haben und diese in SkyPlanner einplanen m\u00f6chten, gehen Sie folgenderma\u00dfen vor: Gehen Sie zur GANTT Timeline, wo die Kapazit\u00e4ten der Arbeitsstationen f\u00fcr diesen Tag nun in lachsfarbener Farbe angezeigt werden, was bedeutet, dass eine Wartung stattfindet. Erledigt! Die Workstation ist jetzt f\u00fcr die Wartung vorgesehen. Wichtig: Klicken Sie auf &#8230; <a title=\"So weisen Sie allen Arbeitsstationen eine vorbeugende Wartung zu\" class=\"read-more\" href=\"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/\" aria-label=\"Mehr Informationen \u00fcber So weisen Sie allen Arbeitsstationen eine vorbeugende Wartung zu\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"doc_category":[1825],"doc_tag":[],"class_list":["post-50250","docs","type-docs","status-publish","hentry","doc_category-workstations-de"],"acf":[],"year_month":"2026-07","word_count":178,"total_views":"158","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"SkyPlanner","author_nicename":"bettina","author_url":"https:\/\/skyplanner.ai\/de\/author\/bettina\/"},"doc_category_info":[{"term_name":"Workstations","term_url":"https:\/\/skyplanner.ai\/de\/docs-category\/workstations-de\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v27.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>So weisen Sie allen Arbeitsstationen eine vorbeugende Wartung zu &#8211; SkyPlanner<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"So weisen Sie allen Arbeitsstationen eine vorbeugende Wartung zu\" \/>\n<meta property=\"og:description\" content=\"Wenn Sie eine vorbeugende Wartung geplant haben und diese in SkyPlanner einplanen m\u00f6chten, gehen Sie folgenderma\u00dfen vor: Gehen Sie zur GANTT Timeline, wo die Kapazit\u00e4ten der Arbeitsstationen f\u00fcr diesen Tag nun in lachsfarbener Farbe angezeigt werden, was bedeutet, dass eine Wartung stattfindet. Erledigt! Die Workstation ist jetzt f\u00fcr die Wartung vorgesehen. Wichtig: Klicken Sie auf ... Weiterlesen ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/\" \/>\n<meta property=\"og:site_name\" content=\"SkyPlanner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T08:52:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/\",\"url\":\"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/\",\"name\":\"So weisen Sie allen Arbeitsstationen eine vorbeugende Wartung zu &#8211; SkyPlanner\",\"isPartOf\":{\"@id\":\"https:\/\/skyplanner.ai\/de\/#website\"},\"datePublished\":\"2025-02-13T10:38:17+00:00\",\"dateModified\":\"2025-10-07T08:52:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skyplanner.ai\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\/\/skyplanner.ai\/de\/docs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"So weisen Sie allen Arbeitsstationen eine vorbeugende Wartung zu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skyplanner.ai\/de\/#website\",\"url\":\"https:\/\/skyplanner.ai\/de\/\",\"name\":\"SkyPlanner\",\"description\":\"AI-powered production scheduling and planning software\",\"publisher\":{\"@id\":\"https:\/\/skyplanner.ai\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skyplanner.ai\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skyplanner.ai\/de\/#organization\",\"name\":\"SkyPlanner APS\",\"url\":\"https:\/\/skyplanner.ai\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/skyplanner.ai\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"contentUrl\":\"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg\",\"width\":223,\"height\":43,\"caption\":\"SkyPlanner APS\"},\"image\":{\"@id\":\"https:\/\/skyplanner.ai\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/skyplanner-aps\/\",\"https:\/\/www.youtube.com\/@SkyPlannerAPS\",\"https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/\",\"https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews\",\"https:\/\/www.saasworthy.com\/product\/skyplanner-aps\",\"https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/\",\"https:\/\/www.g2.com\/products\/skyplanner-aps\/\",\"https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/\",\"https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/\"],\"description\":\"AI-powered production scheduling and planning software for manufacturing\",\"foundingDate\":\"1997\",\"legalName\":\"Skycode Oy\",\"alternateName\":\"SkyPlanner\",\"knowsAbout\":[\"Production Scheduling\",\"Advanced Planning and Scheduling\",\"Manufacturing AI\",\"Finite Capacity Scheduling\",\"ERP Integration\"],\"areaServed\":\"Worldwide\",\"contactPoint\":{\"@type\":\"ContactPoint\",\"contactType\":\"sales\",\"url\":\"https:\/\/skyplanner.ai\/trial\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"So weisen Sie allen Arbeitsstationen eine vorbeugende Wartung zu &#8211; SkyPlanner","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/","og_locale":"de_DE","og_type":"article","og_title":"So weisen Sie allen Arbeitsstationen eine vorbeugende Wartung zu","og_description":"Wenn Sie eine vorbeugende Wartung geplant haben und diese in SkyPlanner einplanen m\u00f6chten, gehen Sie folgenderma\u00dfen vor: Gehen Sie zur GANTT Timeline, wo die Kapazit\u00e4ten der Arbeitsstationen f\u00fcr diesen Tag nun in lachsfarbener Farbe angezeigt werden, was bedeutet, dass eine Wartung stattfindet. Erledigt! Die Workstation ist jetzt f\u00fcr die Wartung vorgesehen. Wichtig: Klicken Sie auf ... Weiterlesen ...","og_url":"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/","og_site_name":"SkyPlanner","article_modified_time":"2025-10-07T08:52:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/","url":"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/","name":"So weisen Sie allen Arbeitsstationen eine vorbeugende Wartung zu &#8211; SkyPlanner","isPartOf":{"@id":"https:\/\/skyplanner.ai\/de\/#website"},"datePublished":"2025-02-13T10:38:17+00:00","dateModified":"2025-10-07T08:52:08+00:00","breadcrumb":{"@id":"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/skyplanner.ai\/de\/docs\/so-weisen-sie-allen-arbeitsplaetzen-eine-vorbeugende-wartung-zu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyplanner.ai\/de\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/skyplanner.ai\/de\/docs\/"},{"@type":"ListItem","position":3,"name":"So weisen Sie allen Arbeitsstationen eine vorbeugende Wartung zu"}]},{"@type":"WebSite","@id":"https:\/\/skyplanner.ai\/de\/#website","url":"https:\/\/skyplanner.ai\/de\/","name":"SkyPlanner","description":"AI-powered production scheduling and planning software","publisher":{"@id":"https:\/\/skyplanner.ai\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyplanner.ai\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/skyplanner.ai\/de\/#organization","name":"SkyPlanner APS","url":"https:\/\/skyplanner.ai\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skyplanner.ai\/de\/#\/schema\/logo\/image\/","url":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","contentUrl":"https:\/\/skyplanner.ai\/wp-content\/uploads\/2022\/05\/Skyplanner-logo-2.svg","width":223,"height":43,"caption":"SkyPlanner APS"},"image":{"@id":"https:\/\/skyplanner.ai\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/skyplanner-aps\/","https:\/\/www.youtube.com\/@SkyPlannerAPS","https:\/\/www.capterra.com\/p\/265911\/SkyPlanner-APS\/","https:\/\/www.trustradius.com\/products\/skyplanner-aps\/reviews","https:\/\/www.saasworthy.com\/product\/skyplanner-aps","https:\/\/sourceforge.net\/software\/product\/SkyPlanner-APS\/","https:\/\/www.g2.com\/products\/skyplanner-aps\/","https:\/\/www.getapp.com\/project-management-planning-software\/a\/skyplanner-aps\/","https:\/\/www.softwareadvice.com\/cmms\/skyplanner-aps-profile\/"],"description":"AI-powered production scheduling and planning software for manufacturing","foundingDate":"1997","legalName":"Skycode Oy","alternateName":"SkyPlanner","knowsAbout":["Production Scheduling","Advanced Planning and Scheduling","Manufacturing AI","Finite Capacity Scheduling","ERP Integration"],"areaServed":"Worldwide","contactPoint":{"@type":"ContactPoint","contactType":"sales","url":"https:\/\/skyplanner.ai\/trial\/"}}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"betterdocs-category-thumb":false},"uagb_author_info":{"display_name":"SkyPlanner","author_link":"https:\/\/skyplanner.ai\/de\/author\/bettina\/"},"uagb_comment_info":0,"uagb_excerpt":"Wenn Sie eine vorbeugende Wartung geplant haben und diese in SkyPlanner einplanen m\u00f6chten, gehen Sie folgenderma\u00dfen vor: Gehen Sie zur GANTT Timeline, wo die Kapazit\u00e4ten der Arbeitsstationen f\u00fcr diesen Tag nun in lachsfarbener Farbe angezeigt werden, was bedeutet, dass eine Wartung stattfindet. Erledigt! Die Workstation ist jetzt f\u00fcr die Wartung vorgesehen. Wichtig: Klicken Sie auf&hellip;","knowledge_base_info":[],"knowledge_base_slug":[],"_links":{"self":[{"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/docs\/50250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/comments?post=50250"}],"version-history":[{"count":0,"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/docs\/50250\/revisions"}],"wp:attachment":[{"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/media?parent=50250"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/doc_category?post=50250"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/skyplanner.ai\/de\/wp-json\/wp\/v2\/doc_tag?post=50250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}